{"id":11587,"date":"2024-08-01T10:18:23","date_gmt":"2024-08-01T02:18:23","guid":{"rendered":"https:\/\/www.minejxsc.com\/?post_type=blog&#038;p=11587"},"modified":"2024-08-02T14:26:19","modified_gmt":"2024-08-02T06:26:19","slug":"what-type-of-mining-was-used-to-find-gold","status":"publish","type":"blog","link":"https:\/\/www.minejxsc.com\/es\/blog\/what-type-of-mining-was-used-to-find-gold\/","title":{"rendered":"\u00bfQu\u00e9 tipo de miner\u00eda se utilizaba para encontrar oro? Una mirada en profundidad"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"11587\" class=\"elementor elementor-11587\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"blog\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ac656a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"1ac656a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8cb65f9\" data-id=\"8cb65f9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12fe350 elementor-widget elementor-widget-pp-breadcrumbs\" data-id=\"12fe350\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;breadcrumbs_type&quot;:&quot;powerpack&quot;}\" data-widget_type=\"pp-breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"pp-breadcrumbs pp-breadcrumbs-powerpack\">\t\t<li class=\"pp-breadcrumbs-item pp-breadcrumbs-item-home\">\n\t\t\t<a class=\"pp-breadcrumbs-crumb pp-breadcrumbs-crumb-link pp-breadcrumbs-crumb-home\" href=\"https:\/\/www.minejxsc.com\/es\" title=\"Inicio\">\n\t\t\t\t<span class=\"pp-breadcrumbs-text\">\n\t\t\t\t\t\t\t\t\t\tInicio\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/li>\n\t\t<li class=\"pp-breadcrumbs-separator\">\t\t\t\t<span class='pp-separator-icon pp-icon'>\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t\t<\/li><\/ul>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6edee60 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6edee60\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-05c1b24\" data-id=\"05c1b24\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51e8347 ha-has-bg-overlay elementor-widget elementor-widget-post-navigation\" data-id=\"51e8347\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-navigation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-post-navigation\" role=\"navigation\" aria-label=\"Navegaci\u00f3n de la entrada\">\n\t\t\t<div class=\"elementor-post-navigation__prev elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/www.minejxsc.com\/es\/blog\/gold-extraction-process\/\" rel=\"prev\"><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-prev\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-left\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.7 239l136-136c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9L127.9 256l96.4 96.4c9.4 9.4 9.4 24.6 0 33.9L201.7 409c-9.4 9.4-24.6 9.4-33.9 0l-136-136c-9.5-9.4-9.5-24.6-.1-34z\"><\/path><\/svg><span class=\"elementor-screen-only\">Ant<\/span><\/span><span class=\"elementor-post-navigation__link__prev\"><span class=\"post-navigation__prev--label\">Anterior<\/span><span class=\"post-navigation__prev--title\">Dominar el proceso de extracci\u00f3n del oro: Consejos de expertos<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-post-navigation__next elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/www.minejxsc.com\/es\/blog\/copper-mining-process\/\" rel=\"next\"><span class=\"elementor-post-navigation__link__next\"><span class=\"post-navigation__next--label\">Siguiente<\/span><span class=\"post-navigation__next--title\">\u00bfQu\u00e9 es el proceso de extracci\u00f3n del cobre? Una visi\u00f3n general paso a paso<\/span><\/span><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-next\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><span class=\"elementor-screen-only\">Siguiente<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-06bb139 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"06bb139\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-524ca79\" data-id=\"524ca79\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e9ad7b elementor-widget elementor-widget-post-info\" data-id=\"8e9ad7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-c57f942 elementor-inline-item\" itemprop=\"author\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.minejxsc.com\/es\/author\/minejxsc\/\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-user-circle\" viewbox=\"0 0 496 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M248 104c-53 0-96 43-96 96s43 96 96 96 96-43 96-96-43-96-96-96zm0 144c-26.5 0-48-21.5-48-48s21.5-48 48-48 48 21.5 48 48-21.5 48-48 48zm0-240C111 8 0 119 0 256s111 248 248 248 248-111 248-248S385 8 248 8zm0 448c-49.7 0-95.1-18.3-130.1-48.4 14.9-23 40.4-38.6 69.6-39.5 20.8 6.4 40.6 9.6 60.5 9.6s39.7-3.1 60.5-9.6c29.2 1 54.7 16.5 69.6 39.5-35 30.1-80.4 48.4-130.1 48.4zm162.7-84.1c-24.4-31.4-62.1-51.9-105.1-51.9-10.2 0-26 9.6-57.6 9.6-31.5 0-47.4-9.6-57.6-9.6-42.9 0-80.6 20.5-105.1 51.9C61.9 339.2 48 299.2 48 256c0-110.3 89.7-200 200-200s200 89.7 200 200c0 43.2-13.9 83.2-37.3 115.9z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-author\">\n\t\t\t\t\t\t\t\t\t\tminejxsc\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-d73c698 elementor-inline-item\" itemprop=\"datePublished\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.minejxsc.com\/es\/2024\/08\/01\/\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-calendar\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M12 192h424c6.6 0 12 5.4 12 12v260c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V204c0-6.6 5.4-12 12-12zm436-44v-36c0-26.5-21.5-48-48-48h-48V12c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v52H160V12c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v52H48C21.5 64 0 85.5 0 112v36c0 6.6 5.4 12 12 12h424c6.6 0 12-5.4 12-12z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-date\">\n\t\t\t\t\t\t\t\t\t\t<time>1 de agosto de 2024<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-24f5706 elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-clock\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm0 448c-110.5 0-200-89.5-200-200S145.5 56 256 56s200 89.5 200 200-89.5 200-200 200zm61.8-104.4l-84.9-61.7c-3.1-2.3-4.9-5.9-4.9-9.7V116c0-6.6 5.4-12 12-12h32c6.6 0 12 5.4 12 12v141.7l66.8 48.6c5.4 3.9 6.5 11.4 2.6 16.8L334.6 349c-3.9 5.3-11.4 6.5-16.8 2.6z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-time\">\n\t\t\t\t\t\t\t\t\t\t<time>10h18<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-da1fb40 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"da1fb40\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-871defa\" data-id=\"871defa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68da466 elementor-widget elementor-widget-heading\" data-id=\"68da466\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfQu\u00e9 es la miner\u00eda de oro?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9a234e elementor-widget elementor-widget-image\" data-id=\"a9a234e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/06\/gold-mine-6.webp\" class=\"attachment-medium_large size-medium_large wp-image-10596\" alt=\"mina de oro (6)\" srcset=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/06\/gold-mine-6.webp 1024w, https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/06\/gold-mine-6-600x450.webp 600w, https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/06\/gold-mine-6-768x576.webp 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a41bd0e elementor-widget elementor-widget-text-editor\" data-id=\"a41bd0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div data-page-id=\"LmUPdA5ghoHGKvxCuSbcVEginrD\" data-docx-has-block-data=\"false\"><div class=\"ace-line ace-line old-record-id-FyzQdtYKBosnxUxyV6KcdTl0ngd\"><div data-page-id=\"MAIkdlhzEotUVvxURuYcWuxjnrh\" data-docx-has-block-data=\"false\"><div>\u00a0<\/div><div class=\"ace-line ace-line old-record-id-P79ydoBdIo0SHgxzbLNcQdmGnfe\">La miner\u00eda del oro consiste en extraer oro de la tierra a partir de su mineral. Para ello se utilizan distintos m\u00e9todos, todos ellos espec\u00edficos seg\u00fan las condiciones geol\u00f3gicas y la escala de la operaci\u00f3n. El oro, que parece un metal precioso, ha impulsado la b\u00fasqueda y el descubrimiento por parte del hombre durante siglos, lo que dio lugar a importantes acontecimientos hist\u00f3ricos como la Fiebre del Oro de California y la Fiebre del Oro de Klondike. Estos acontecimientos no s\u00f3lo afectaron a la industria minera, sino que tambi\u00e9n repercutieron en el movimiento y desarrollo de poblaciones de todos los continentes.<\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54f24fd elementor-widget elementor-widget-heading\" data-id=\"54f24fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Miner\u00eda de oro a peque\u00f1a y gran escala<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a04393d elementor-widget__width-initial pp-table-center elementor-widget elementor-widget-pp-table\" data-id=\"a04393d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;table_type&quot;:&quot;responsive&quot;,&quot;scrollable&quot;:&quot;no&quot;}\" data-widget_type=\"pp-table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"pp-table-container\">\n\t\t\t<table \n\t\t\tclass=\"pp-table tablesaw\" data-tablesaw-mode=\"stack\"\t\t\t\t>\n\t\t\t\t\t\t\t<colgroup>\n\t\t\t\t\t\t\t\t<col\n\t\t\t\t\tspan=\"1\"\n\t\t\t\t\tclass=\"elementor-repeater-item-32d7a45\"\n\t\t\t\t\t\t\t\t\t\t\tstyle=\"\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\"\n\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t<\/colgroup>\n\t\t\t\t\t\t<thead>\n\t\t\t\t<tr class=\"pp-table-row\">\n\t\t\t\t\t<th class=\"pp-table-cell pp-table-cell-8cf5bb8\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Aspecto<\/span><\/span><\/th><th class=\"pp-table-cell pp-table-cell-061a599\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Miner\u00eda de oro a peque\u00f1a escala<\/span><\/span><\/th><th class=\"pp-table-cell pp-table-cell-e74032a\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Miner\u00eda de oro a gran escala<\/span><\/span><\/th>\t\t\t\t<\/tr>\n\t\t\t<\/thead>\n\t\t\t\t\t<tfoot>\n\t\t\t<\/tr>\t\t<\/tfoot>\n\t\t\t\t<tbody>\n\t\t\t<tr ><td class=\"pp-table-cell pp-table-cell-524b949\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Coste de inversi\u00f3n\t<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-eb9c69c\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Bajo coste de inversi\u00f3n, accesible a particulares y peque\u00f1os grupos.\t<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-560abde\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Alto coste de inversi\u00f3n, que requiere un capital y una infraestructura considerables.<\/span><\/span><\/td><\/tr><tr ><td class=\"pp-table-cell pp-table-cell-8b9591a\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Escala de operaciones\t<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-8f39f58\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Opera a menor escala, a menudo en zonas localizadas.\t<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-1b179b9\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Opera a gran escala, abarcando extensas zonas.<\/span><\/span><\/td><\/tr><tr ><td class=\"pp-table-cell pp-table-cell-ca30337\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Equipamiento t\u00edpico\t<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-f87fcd7\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Herramientas sencillas como bateas, esclusas, cajas basculantes y, a veces, peque\u00f1as dragas. Se utilizan equipos de trituraci\u00f3n y m\u00e9todos sencillos de tratamiento del mineral.\t<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-c9528e3\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Equipos avanzados como grandes dragas, highbankers, maquinaria pesada, trituradoras y sofisticadas plantas de procesamiento.<\/span><\/span><\/td><\/tr><tr ><td class=\"pp-table-cell pp-table-cell-5a75982\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Impacto medioambiental\t<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-3bc7156\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Impacto generalmente menor, pero puede causar da\u00f1os medioambientales localizados.\t<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-b2c4b84\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Mayor impacto ambiental debido a las operaciones a gran escala y al uso de productos qu\u00edmicos.<\/span><\/span><\/td><\/tr><tr ><td class=\"pp-table-cell pp-table-cell-bd67e35\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Riesgos sanitarios\t<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-4bf49fe\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Mayores riesgos para la salud debido a la falta de protocolos de seguridad y a la exposici\u00f3n al mercurio.\t<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-843226c\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Gesti\u00f3n de riesgos sanitarios con protocolos de seguridad.<\/span><\/span><\/td><\/tr><tr ><td class=\"pp-table-cell pp-table-cell-80bbe87\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Beneficios econ\u00f3micos\t<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-ad55a63\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Proporciona ingresos de subsistencia a los mineros y sus familias.\t<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-fe13e50\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Genera beneficios econ\u00f3micos sustanciales, incluidos el empleo y el desarrollo regional.\t<\/span><\/span><\/td><\/tr><tr ><td class=\"pp-table-cell pp-table-cell-38ee31c\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Participaci\u00f3n comunitaria\t<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-e6c7365\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Gran implicaci\u00f3n de las comunidades locales y los pueblos ind\u00edgenas.<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-e5cfb2a\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Implica a las comunidades locales principalmente a trav\u00e9s del empleo y de iniciativas de responsabilidad social corporativa.<\/span><\/span><\/td><\/tr>\t\t<\/tbody>\n\t\t\t\t\t<\/table>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-286812d elementor-widget elementor-widget-heading\" data-id=\"286812d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Evoluci\u00f3n hist\u00f3rica de las t\u00e9cnicas de extracci\u00f3n de oro<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff1daba elementor-widget elementor-widget-image\" data-id=\"ff1daba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/06\/gold-formed.webp\" class=\"attachment-medium_large size-medium_large wp-image-10453\" alt=\"oro\" srcset=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/06\/gold-formed.webp 1024w, https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/06\/gold-formed-600x450.webp 600w, https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/06\/gold-formed-768x576.webp 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1de113c elementor-widget elementor-widget-text-editor\" data-id=\"1de113c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div data-page-id=\"Yl47dAsdgoEvOoxtS03cMQ5onRe\" data-docx-has-block-data=\"false\"><div data-page-id=\"H6JSdhirYoXlGTxqhXGcYwJanmg\" data-docx-has-block-data=\"false\"><div class=\"ace-line ace-line old-record-id-JrIZdmdPmoNKhVxUc1lcuwHunZo\"><div data-page-id=\"MRi2dXn2AoApXWxxjyjcQIuanjg\" data-docx-has-block-data=\"false\"><div data-page-id=\"MAIkdlhzEotUVvxURuYcWuxjnrh\" data-docx-has-block-data=\"false\"><div class=\"ace-line ace-line old-record-id-A7ded4mbLomtbcxvaTgcq6yUnff\">Los m\u00e9todos de extracci\u00f3n de oro han cambiado a lo largo de los a\u00f1os. En el pasado, los mineros utilizaban t\u00e9cnicas b\u00e1sicas como el bateo de oro, que es el proceso de utilizar un recipiente poco profundo conocido como batea de oro para tamizar los sedimentos del r\u00edo y encontrar oro. Este m\u00e9todo era pr\u00e1ctico para los primeros buscadores que trabajaban a peque\u00f1a escala. Con el avance de la tecnolog\u00eda, se descubrieron t\u00e9cnicas mejores. En el siglo XIX se adopt\u00f3 la miner\u00eda hidr\u00e1ulica, en la que se utilizaba la presi\u00f3n del agua para derribar el material rocoso y lavar el oro. Sin embargo, este m\u00e9todo era muy destructivo para el medio ambiente, por lo que se adoptaron medidas m\u00e1s estrictas.<\/div><div>\u00a0<\/div><div class=\"ace-line ace-line old-record-id-Lm3IdZMeWoP1pWxDBJfcwNPDn3g\">Durante el siglo XX, las t\u00e9cnicas mineras como la miner\u00eda subterr\u00e1nea y la miner\u00eda a cielo abierto fueron comunes en la miner\u00eda de roca dura. Estos m\u00e9todos permitieron a los mineros llegar a vetas aur\u00edferas m\u00e1s profundas y complejas. Las nuevas tecnolog\u00edas en maquinaria y productos qu\u00edmicos mejoraron la extracci\u00f3n de oro y fomentaron la producci\u00f3n a gran escala. En la actualidad, se utilizan t\u00e9cnicas como la lixiviaci\u00f3n con cianuro y el dragado mejorado para mejorar la eficacia de la extracci\u00f3n de oro y, al mismo tiempo, disminuir la cantidad de esfuerzo necesario. Se trata de un proceso continuo, indicativo del intento de la industria de satisfacer la creciente demanda de oro mediante la innovaci\u00f3n tecnol\u00f3gica y la capacidad de vender su oro a precios m\u00e1s altos.<\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e6c7cb4 elementor-widget elementor-widget-heading\" data-id=\"e6c7cb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Diferentes tipos de extracci\u00f3n de oro<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e343cba elementor-widget elementor-widget-image\" data-id=\"e343cba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/07\/gravity-separation-method-3.webp\" class=\"attachment-medium_large size-medium_large wp-image-11123\" alt=\"mina de oro\" srcset=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/07\/gravity-separation-method-3.webp 1024w, https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/07\/gravity-separation-method-3-600x450.webp 600w, https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/07\/gravity-separation-method-3-768x576.webp 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7653fb elementor-widget elementor-widget-text-editor\" data-id=\"c7653fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La miner\u00eda del oro puede clasificarse en dos grandes tipos: miner\u00eda de placer y miner\u00eda de roca dura. Cada m\u00e9todo cuenta con t\u00e9cnicas y equipos distintos que se adaptan a condiciones geol\u00f3gicas diferentes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ad5346 elementor-widget elementor-widget-heading\" data-id=\"2ad5346\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Miner\u00eda de oro de platera<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-881f0a4 elementor-widget elementor-widget-text-editor\" data-id=\"881f0a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La miner\u00eda de placer se centra en los yacimientos de oro que se encuentran en dep\u00f3sitos aluviales, que son materiales sueltos en los lechos de r\u00edos y arroyos. He aqu\u00ed algunas t\u00e9cnicas clave:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b57272 elementor-widget elementor-widget-text-editor\" data-id=\"2b57272\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div data-page-id=\"MAIkdlhzEotUVvxURuYcWuxjnrh\" data-docx-has-block-data=\"false\"><div class=\"ace-line ace-line old-record-id-S62sdK0FgoFhDHxEgBjcsSZ5n0d\"><strong>\u25cf Paneo de oro:<\/strong> El bateo de oro es el m\u00e9todo m\u00e1s b\u00e1sico de la miner\u00eda de placer en el que los mineros emplean un bateador de oro para lavar el oro de otros materiales en fuentes de agua. Este m\u00e9todo, que se practica desde el Imperio Romano, sigue utiliz\u00e1ndose hoy en d\u00eda porque es barato y f\u00e1cil de practicar. Lo practican habitualmente los lugare\u00f1os y la poblaci\u00f3n ind\u00edgena. Aunque no es muy eficaz cuando se realiza a gran escala, sigue siendo el m\u00e9todo preferido para localizar pepitas y monedas de oro.<\/div><div>\u00a0<\/div><div class=\"ace-line ace-line old-record-id-M4bmdGuTIoK58RxtRnMcXDl7nrh\"><strong>\u25cf Sluicing:<\/strong> La esclusa sirve para extraer el oro de la grava y la arena de los yacimientos aluviales. El flujo de agua a trav\u00e9s de la caja ayuda a atrapar los minerales m\u00e1s pesados, como el oro. Este m\u00e9todo es m\u00e1s eficaz que el bateo y se utiliza habitualmente en Norteam\u00e9rica y la Columbia Brit\u00e1nica. Los m\u00e9todos modernos lo han hecho m\u00e1s eficaz y se utiliza mucho en los yacimientos de oro.<\/div><div>\u00a0<\/div><div class=\"ace-line ace-line old-record-id-MkfWdYiGsoUg48x3uU5cbt4Knvg\"><strong>\u25cf Caja basculante:<\/strong> La caja oscilante o cuna es otro de los primeros m\u00e9todos de miner\u00eda aluvial, un cruce entre el bateo y el esclusaje. Los mineros sacuden la caja de un lado a otro para que el agua y la grava fluyan mientras atrapan el oro. Este m\u00e9todo se ha utilizado durante la fiebre del oro y es hist\u00f3ricamente relevante y ha sido parte de las mejores pr\u00e1cticas en la miner\u00eda de placer.<\/div><div>\u00a0<\/div><div class=\"ace-line ace-line old-record-id-RL6EdsZb0ovMB0xGX9FccI98nAh\"><strong>\u25cf Dragado: <\/strong>La miner\u00eda hidr\u00e1ulica es un m\u00e9todo que utiliza el agua para transportar el oro de la superficie de los dep\u00f3sitos aluviales a trav\u00e9s de grandes m\u00e1quinas. Este m\u00e9todo es adecuado para la extracci\u00f3n a gran escala y se ha practicado en distintas partes del mundo, como el sur de \u00c1frica y el Nuevo Mundo. Sin embargo, tiene algunas repercusiones para la salud de la poblaci\u00f3n local y el medio ambiente, aunque es eficaz.<\/div><div>\u00a0<\/div><div class=\"ace-line ace-line old-record-id-Xb6GdFl0NoV1qkx6mKicLFBCn7J\"><strong>\u25cf Highbanking: <\/strong>El bateo alto es un m\u00e9todo en el que un bateador alto, una esclusa con una bomba, se lleva al lugar de extracci\u00f3n. Este m\u00e9todo puede utilizarse para la extracci\u00f3n de oro no s\u00f3lo cerca de las fuentes naturales de agua, sino en cualquier otro tipo de territorio. El highbanking es una t\u00e9cnica contempor\u00e1nea adecuada para explotaciones a gran escala.<\/div><div>\u00a0<\/div><div class=\"ace-line ace-line old-record-id-ObfUdPa4Oos1e4xAB5zcKt6JnSh\"><strong>\u25cf Lavado en seco: <\/strong>El lavado en seco se aplica cuando no se dispone de agua o \u00e9sta escasea, como ocurre en las zonas des\u00e9rticas. Este m\u00e9todo emplea aire para aislar el oro de otros materiales, ya que el oro es m\u00e1s denso que otros sedimentos. Es especialmente aplicable en zonas como el sur de \u00c1frica y ofrece una alternativa de bajo coste para la extracci\u00f3n de oro.<\/div><div>\u00a0<\/div><div class=\"ace-line ace-line old-record-id-SXSGdtCqcoos6Oxe0mtceBlZndg\"><strong>\u25cf F\u00e1bricas de sellos:<\/strong> Aunque no es un m\u00e9todo importante de la miner\u00eda de placer, los molinos de estampaci\u00f3n se utilizan para triturar el mineral y liberar la mina de oro del placer. Esta t\u00e9cnica se utiliz\u00f3 ampliamente durante las hist\u00f3ricas fiebre del oro y se ha modificado para las pr\u00e1cticas contempor\u00e1neas con el fin de aumentar la productividad.<\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da9ce0d elementor-widget elementor-widget-heading\" data-id=\"da9ce0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Miner\u00eda de roca dura<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-313f7c6 elementor-widget elementor-widget-text-editor\" data-id=\"313f7c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div data-page-id=\"MAIkdlhzEotUVvxURuYcWuxjnrh\" data-docx-has-block-data=\"false\"><div class=\"ace-line ace-line old-record-id-UK3Sd91E9otspRxYtfAccGrEnUf\">La miner\u00eda de roca dura extrae el oro de formaciones rocosas s\u00f3lidas. Incluye dos m\u00e9todos principales:<\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5eed832 elementor-widget elementor-widget-text-editor\" data-id=\"5eed832\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div data-page-id=\"MAIkdlhzEotUVvxURuYcWuxjnrh\" data-docx-has-block-data=\"false\"><div class=\"ace-line ace-line old-record-id-Y7ccdqK4To5XjpxygXlcUl0GnWe\"><strong>\u25cf Miner\u00eda subterr\u00e1nea: <\/strong>La perforaci\u00f3n de t\u00faneles y pozos es un tipo de miner\u00eda subterr\u00e1nea para extraer oro de las profundidades de la tierra. Este m\u00e9todo permite llegar a yacimientos de oro ricos y profundos que no pueden explotarse con el m\u00e9todo de miner\u00eda aluvial. Requiere mucho capital y tecnolog\u00eda sofisticada, por lo que es m\u00e1s apropiado para la producci\u00f3n a gran escala. Debido a la naturaleza qu\u00edmica del oro, es necesario emplear m\u00e9todos espec\u00edficos para extraerlo y purificarlo.<\/div><div>\u00a0<\/div><div class=\"ace-line ace-line old-record-id-KaIsdROXtoWdM7x9yv4cqLASnLd\"><strong>\u25cf Miner\u00eda a cielo abierto: <\/strong>La miner\u00eda a cielo abierto es uno de los primeros m\u00e9todos desarrollados para extraer oro de grandes yacimientos cercanos a la superficie. Este m\u00e9todo, el m\u00e1s com\u00fan, consiste en arrancar grandes cantidades de escombros para llegar al mineral. Este m\u00e9todo, eficaz y a gran escala, es el que emplean las grandes empresas mineras. Las grandes minas a cielo abierto se encuentran en Norteam\u00e9rica y otras zonas con grandes yacimientos de oro. Aunque puede producir mucho oro, presenta muchos problemas medioambientales y debe gestionarse bien para evitar efectos adversos para la salud de las personas que viven cerca.<\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b8faa5 elementor-widget elementor-widget-text-editor\" data-id=\"2b8faa5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00bfTiene curiosidad por saber c\u00f3mo se procesan y extraen estas minas de oro? Haga clic para \"<a href=\"https:\/\/www.minejxsc.com\/es\/blog\/gold-mining-processes\/\">Comprender el proceso de extracci\u00f3n del oro: Una gu\u00eda completa<\/a>\" y \"<a href=\"https:\/\/www.minejxsc.com\/es\/blog\/gold-extraction-process\/\">Dominar el proceso de extracci\u00f3n del oro: Consejos de expertos<\/a>\" en detalle.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e364e5 elementor-widget elementor-widget-heading\" data-id=\"1e364e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Herramientas y maquinaria innovadoras en la miner\u00eda del oro moderna<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a3dc25b elementor-widget elementor-widget-image\" data-id=\"a3dc25b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/03\/cone-crusher-1.webp\" class=\"attachment-medium_large size-medium_large wp-image-9502\" alt=\"trituradora de cono\" srcset=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/03\/cone-crusher-1.webp 1024w, https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/03\/cone-crusher-1-600x450.webp 600w, https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/03\/cone-crusher-1-768x576.webp 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5e7e9d elementor-widget elementor-widget-text-editor\" data-id=\"e5e7e9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div data-page-id=\"MAIkdlhzEotUVvxURuYcWuxjnrh\" data-docx-has-block-data=\"false\"><div class=\"ace-line ace-line old-record-id-BxSmdT5PVojwacxmPF4cpLxlnBd\"><div data-page-id=\"MAIkdlhzEotUVvxURuYcWuxjnrh\" data-docx-has-block-data=\"false\"><div class=\"ace-line ace-line old-record-id-KlZJdgM91onCTdxpXjHc0wxcn1d\"><strong>\u25cf<a href=\"https:\/\/www.minejxsc.com\/es\/mineral-processing-equipment\/rock-crushers\/\"> Trituradoras<\/a>: <\/strong>Triturar grandes rocas en otras m\u00e1s peque\u00f1as facilita el proceso de extracci\u00f3n del mineral de oro y aumenta la eficacia del proceso. Las trituradoras de mand\u00edbulas se utilizan tanto en operaciones de miner\u00eda de roca dura como de placer, ya que ayudan a descomponer el mineral en tama\u00f1os m\u00e1s peque\u00f1os.<\/div><div>\u00a0<\/div><div class=\"ace-line ace-line old-record-id-EwTkdLHfUoIMVDxCnX9c0t4An1c\"><strong>\u25cf <a href=\"https:\/\/www.minejxsc.com\/es\/mineral-sprocessing-plants\/gravity-separators\/\">Concentradores de gravedad<\/a>: <\/strong>La gravedad ayuda en el proceso de separaci\u00f3n de las part\u00edculas de oro que son m\u00e1s densas que otros materiales. Estos dispositivos son muy eficaces en la recuperaci\u00f3n de oro fino y se utilizan ampliamente tanto en la miner\u00eda a peque\u00f1a como a gran escala.<\/div><div>\u00a0<\/div><div class=\"ace-line ace-line old-record-id-Zz70djD5MoZ1vux9z3qczc8xnJb\"><strong>\u25cf <a href=\"https:\/\/www.minejxsc.com\/es\/mineral-processing-equipment\/magnetic-separators\/\">Separadores magn\u00e9ticos<\/a>: <\/strong>Separaci\u00f3n magn\u00e9tica: este proceso ayuda a eliminar los materiales magn\u00e9ticos del mineral, mejorando as\u00ed la calidad del producto final. Estos separadores son especialmente \u00fatiles cuando se trabaja con mineral que contiene una gran proporci\u00f3n de materiales magn\u00e9ticos; de este modo, s\u00f3lo quedan el oro y otros metales valiosos.<\/div><div>\u00a0<\/div><div class=\"ace-line ace-line old-record-id-NvVhd5ukYompG0xc9YvcRG3knRc\"><strong>\u25cf Dragas: <\/strong>Equipo empleado en la miner\u00eda aluvial para succionar sedimentos del fondo de los r\u00edos con grandes m\u00e1quinas de succi\u00f3n. Son muy eficaces en la extracci\u00f3n de oro de yacimientos submarinos y permiten a los mineros trabajar a trav\u00e9s de una gran cantidad de material.<\/div><div>\u00a0<\/div><div class=\"ace-line ace-line old-record-id-CEXQdfkSroW319xtRHcc0OOsnVh\"><strong>\u25cf <\/strong><a href=\"https:\/\/www.minejxsc.com\/es\/mineral-processing-equipment\/flotation-machines\/\"><strong>Flotaci\u00f3n<\/strong><\/a><strong> C\u00e9lulas: <\/strong>M\u00e1quina que emplea el uso de reactivos qu\u00edmicos y burbujas de aire para aislar el oro de otros minerales. La flotaci\u00f3n es particularmente aplicable al tratamiento de menas de sulfuro en las que el oro est\u00e1 diseminado en el mineral en part\u00edculas muy finas.<\/div><div>\u00a0<\/div><div class=\"ace-line ace-line old-record-id-FJCHdJLdtot6g8xoCaQcGOrbnJe\"><strong>\u25cf Tanques de lixiviaci\u00f3n de cianuro:<\/strong> Se emplea en el proceso de disoluci\u00f3n del oro en una soluci\u00f3n de cianuro con el fin de recuperar el metal de su mena. Este m\u00e9todo es muy eficaz en la extracci\u00f3n de oro a partir de minerales de baja ley y est\u00e1 en pr\u00e1ctica en la mayor\u00eda de las industrias mineras actuales.<\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f4fd3b elementor-widget elementor-widget-text-editor\" data-id=\"3f4fd3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div data-page-id=\"MAIkdlhzEotUVvxURuYcWuxjnrh\" data-docx-has-block-data=\"false\"><div class=\"ace-line ace-line old-record-id-UTHWdlcD1ofGZyxY5ezc6gYGnuf\"><a href=\"https:\/\/www.minejxsc.com\/es\/\">F\u00e1brica de maquinaria minera de JXSC<\/a> es un fabricante de equipos de miner\u00eda de oro que suministra trituradoras, concentradores gravim\u00e9tricos y separadores magn\u00e9ticos. Elogiados por su rapidez y eficacia <a href=\"https:\/\/www.minejxsc.com\/es\/mineral-processing-equipment\/\">equipo de tratamiento de oro<\/a>JXSC garantiza una alta productividad y durabilidad en la miner\u00eda del oro.<\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ada96eb elementor-align-center elementor-widget elementor-widget-button\" data-id=\"ada96eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ2NTUiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenga un presupuesto gratuito<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d7ac98 elementor-widget elementor-widget-heading\" data-id=\"7d7ac98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Conclusi\u00f3n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4d177a elementor-widget elementor-widget-text-editor\" data-id=\"f4d177a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div data-page-id=\"MAIkdlhzEotUVvxURuYcWuxjnrh\" data-docx-has-block-data=\"false\"><div class=\"ace-line ace-line old-record-id-GAHzdl6hvoOBhWxFPzMcS654nPh\">El desarrollo tecnol\u00f3gico en la miner\u00eda del oro ha seguido avanzando con inventos como los sistemas automatizados de perforaci\u00f3n que mejoran la precisi\u00f3n y la velocidad. La IA y el aprendizaje autom\u00e1tico mejoran la b\u00fasqueda y las posibilidades de encontrar yacimientos de oro son m\u00e1s precisas. La biolixiviaci\u00f3n y la concentraci\u00f3n gravim\u00e9trica avanzada son algunas de las t\u00e9cnicas de procesamiento que mejoran las tasas de recuperaci\u00f3n en el mundo moderno. Estas innovaciones aumentan la eficiencia y la eficacia en las operaciones, incrementando as\u00ed la rentabilidad de la miner\u00eda del oro.<\/div><div>\u00a0<\/div><div class=\"ace-line ace-line old-record-id-CiLidygktoyZhHxkq45c9fnVnzf\"><a href=\"https:\/\/www.minejxsc.com\/es\/\">F\u00e1brica de maquinaria minera de JXSC<\/a> est\u00e1 a la vanguardia de estas innovaciones, proporcionando <a href=\"https:\/\/www.minejxsc.com\/es\/gold\/\">soluciones para la extracci\u00f3n de oro<\/a> que integran tecnolog\u00edas avanzadas. Ser un profesional <a href=\"https:\/\/www.minejxsc.com\/es\/mineral-processing-equipment\/\">equipos de tratamiento de minerales<\/a> fabricante, <a href=\"https:\/\/www.minejxsc.com\/es\/\">JXSC<\/a> se asegura de que sus clientes dispongan de las \u00faltimas tecnolog\u00edas para ayudarles a obtener los mejores resultados en sus operaciones mineras con equipos duraderos y de alto rendimiento.<\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70cf4dc elementor-align-center elementor-widget elementor-widget-button\" data-id=\"70cf4dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ2NTUiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">P\u00f3ngase en contacto con nosotros<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8810e8b elementor-widget elementor-widget-heading\" data-id=\"8810e8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Preguntas frecuentes<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddef2d1 elementor-widget elementor-widget-pp-faq\" data-id=\"ddef2d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;faq_layout&quot;:&quot;accordion&quot;,&quot;accordion_type&quot;:&quot;accordion&quot;,&quot;toggle_speed&quot;:300}\" data-widget_type=\"pp-faq.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"pp-faqs pp-advanced-accordion pp-toggle-icon-align-right\" id=\"pp-advanced-accordion-ddef2d1\" data-accordion-id=\"ddef2d1\">\n\t\t\t\t\t\t<div class=\"pp-faq-item elementor-grid-item pp-accordion-item\">\n\t\t\t\t<div id=\"pp-accordion-tab-title-2321\" class=\"pp-faq-question pp-accordion-tab-title\" tabindex=\"0\" data-tab=\"1\">\n\t\t\t\t\t<div class=\"pp-accordion-title-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-accordion-title-text\">\n\t\t\t\t\t\t\t\u00bfCu\u00e1les son las repercusiones medioambientales de los distintos m\u00e9todos de extracci\u00f3n de oro?\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-accordion-toggle-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-close pp-icon'>\n\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-open pp-icon'>\n\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"pp-accordion-tab-content-2321\" class=\"pp-faq-answer pp-accordion-tab-content\" data-tab=\"1\">\n\t\t\t\t\t<div data-page-id=\"NfjtdkvF8odsI2xEU2PcBCwynQd\" data-docx-has-block-data=\"false\">\n<div class=\"ace-line ace-line old-record-id-CTr6duS1OoUiNoxpLcNcgWcanic\">\n<div data-page-id=\"EQ7fdqFpcoErfDxCDQOcz0hYnTg\" data-docx-has-block-data=\"false\">\n<div class=\"ace-line ace-line old-record-id-SI91d7XgFoQfNZxZ6AxcHqK9nSe\">\n<div data-page-id=\"I2zNd29yEoiDgpxKUWRcUVl7nmg\" data-docx-has-block-data=\"false\">\n<div class=\"ace-line ace-line old-record-id-Sh3sdxR4Jo39dpx90FCcr1zfnMb\">\n<div data-page-id=\"H6JSdhirYoXlGTxqhXGcYwJanmg\" data-docx-has-block-data=\"false\">\n<div class=\"ace-line ace-line old-record-id-RdvbdRJhzoZOSwxJ4HUcFySCnZf\">\n<div data-page-id=\"CkHWdaXJzoOkqMxh0SLcVAXYnBb\" data-docx-has-block-data=\"false\">\n<div class=\"ace-line ace-line old-record-id-OTZddUdI8oY0pOxNcTNc6Ur4nyg\">\n<div data-page-id=\"MAIkdlhzEotUVvxURuYcWuxjnrh\" data-docx-has-block-data=\"false\">\n<div class=\"ace-line ace-line old-record-id-LpTedcoX6okmCpxLiIocuihknoh\">El m\u00e9todo de la miner\u00eda de aluvi\u00f3n es muy destructivo para los h\u00e1bitats fluviales y los reg\u00edmenes sedimentarios debido a la alteraci\u00f3n de los sedimentos. Esta forma de miner\u00eda provoca la p\u00e9rdida de la cubierta vegetal y la contaminaci\u00f3n del suelo y el agua por metales pesados y productos qu\u00edmicos como el cianuro y el mercurio utilizados en la extracci\u00f3n de los minerales.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"pp-faq-item elementor-grid-item pp-accordion-item\">\n\t\t\t\t<div id=\"pp-accordion-tab-title-2322\" class=\"pp-faq-question pp-accordion-tab-title\" tabindex=\"0\" data-tab=\"2\">\n\t\t\t\t\t<div class=\"pp-accordion-title-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-accordion-title-text\">\n\t\t\t\t\t\t\t\u00bfC\u00f3mo se procesa el oro una vez extra\u00eddo?\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-accordion-toggle-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-close pp-icon'>\n\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-open pp-icon'>\n\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"pp-accordion-tab-content-2322\" class=\"pp-faq-answer pp-accordion-tab-content\" data-tab=\"2\">\n\t\t\t\t\t<div data-page-id=\"CkHWdaXJzoOkqMxh0SLcVAXYnBb\" data-docx-has-block-data=\"false\">\n<div class=\"ace-line ace-line old-record-id-HnIAd97OGo2cr7xTt1dcN9eHnfb\">Una vez extra\u00eddo, el oro se tritura y se muele hasta obtener un polvo fino. A continuaci\u00f3n, el oro se extrae mediante m\u00e9todos como la concentraci\u00f3n por gravedad, la flotaci\u00f3n o el proceso de cianuraci\u00f3n. A continuaci\u00f3n, el oro extra\u00eddo se somete al proceso de fundici\u00f3n en el que se separan las impurezas del oro para obtener oro de gran pureza.<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2992ba2 ignore-toc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2992ba2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-faa3aec\" data-id=\"faa3aec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b9f58ed elementor-widget elementor-widget-heading\" data-id=\"b9f58ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Comparte:<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e314bd4\" data-id=\"e314bd4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e90e316 elementor-share-buttons--view-icon elementor-share-buttons--shape-rounded elementor-share-buttons--skin-gradient elementor-grid-0 elementor-share-buttons--color-official elementor-widget elementor-widget-share-buttons\" data-id=\"e90e316\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_facebook\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur facebook\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_linkedin\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur linkedin\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_twitter\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur twitter\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-twitter\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M459.37 151.716c.325 4.548.325 9.097.325 13.645 0 138.72-105.583 298.558-298.558 298.558-59.452 0-114.68-17.219-161.137-47.106 8.447.974 16.568 1.299 25.34 1.299 49.055 0 94.213-16.568 130.274-44.832-46.132-.975-84.792-31.188-98.112-72.772 6.498.974 12.995 1.624 19.818 1.624 9.421 0 18.843-1.3 27.614-3.573-48.081-9.747-84.143-51.98-84.143-102.985v-1.299c13.969 7.797 30.214 12.67 47.431 13.319-28.264-18.843-46.781-51.005-46.781-87.391 0-19.492 5.197-37.36 14.294-52.954 51.655 63.675 129.3 105.258 216.365 109.807-1.624-7.797-2.599-15.918-2.599-24.04 0-57.828 46.782-104.934 104.934-104.934 30.213 0 57.502 12.67 76.67 33.137 23.715-4.548 46.456-13.32 66.599-25.34-7.798 24.366-24.366 44.833-46.132 57.827 21.117-2.273 41.584-8.122 60.426-16.243-14.292 20.791-32.161 39.308-52.628 54.253z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_pinterest\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur pinterest\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-pinterest\" viewbox=\"0 0 496 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M496 256c0 137-111 248-248 248-25.6 0-50.2-3.9-73.4-11.1 10.1-16.5 25.2-43.5 30.8-65 3-11.6 15.4-59 15.4-59 8.1 15.4 31.7 28.5 56.8 28.5 74.8 0 128.7-68.8 128.7-154.3 0-81.9-66.9-143.2-152.9-143.2-107 0-163.9 71.8-163.9 150.1 0 36.4 19.4 81.7 50.3 96.1 4.7 2.2 7.2 1.2 8.3-3.3.8-3.4 5-20.3 6.9-28.1.6-2.5.3-4.7-1.7-7.1-10.1-12.5-18.3-35.3-18.3-56.6 0-54.7 41.4-107.6 112-107.6 60.9 0 103.6 41.5 103.6 100.9 0 67.1-33.9 113.6-78 113.6-24.3 0-42.6-20.1-36.7-44.8 7-29.5 20.5-61.3 20.5-82.6 0-19-10.2-34.9-31.4-34.9-24.9 0-44.9 25.7-44.9 60.2 0 22 7.4 36.8 7.4 36.8s-24.5 103.8-29 123.2c-5 21.4-3 51.6-.9 71.2C65.4 450.9 0 361.1 0 256 0 119 111 8 248 8s248 111 248 248z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8a849cb ignore-toc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8a849cb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-97e555f\" data-id=\"97e555f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1298b81 elementor-widget elementor-widget-heading\" data-id=\"1298b81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Entradas relacionadas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67af1fc elementor-grid-4 elementor-grid-tablet-2 elementor-grid-mobile-1 pp-equal-height-yes elementor-widget elementor-widget-pp-posts\" data-id=\"67af1fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-posts.portfolio\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"pp-posts-container\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t<div class=\"pp-posts pp-posts-skin-portfolio elementor-grid pp-posts-grid\" data-query-type=\"custom\" data-layout=\"grid\" data-page=\"11587\" data-skin=\"portfolio\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-post-wrap pp-grid-item-wrap elementor-grid-item post-55420 blog type-blog status-publish has-post-thumbnail hentry category-mineral-solution\">\n\t\t\t\t\t\t<div class=\"pp-post pp-grid-item\">\n\t\t\t\t<div class=\"pp-post-content pp-content-always\">\n\t\t\t\t\t\t\t<div class=\"pp-post-thumbnail\">\n\t\t\t<a class=\"pp-post-thumbnail-wrap\" href=\"https:\/\/www.minejxsc.com\/es\/blog\/4-common-silica-sand-impurities-best-removal-methods\/\" title=\"4\u00a0Common Silica Sand Impurities &amp; Best Removal Methods\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2026\/05\/Silica-Sand-Impurities.jpg\" class=\"attachment-large size-large wp-image-55421\" alt=\"Silica Sand Impurities\" srcset=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2026\/05\/Silica-Sand-Impurities.jpg 1024w, https:\/\/www.minejxsc.com\/wp-content\/uploads\/2026\/05\/Silica-Sand-Impurities-16x12.jpg 16w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"pp-image-overlay\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"pp-post-thumb-content-wrap\">\n\t\t\t\t\t\t<div class=\"pp-post-thumb-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"pp-post-title\">\n\t\t\t\t<a href=\"https:\/\/www.minejxsc.com\/es\/blog\/4-common-silica-sand-impurities-best-removal-methods\/\" target=\"_blank\">4\u00a0Common Silica Sand Impurities &amp; Best Removal Methods<\/a>\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t<div class=\"pp-post-meta\">\n\t\t\t\t\t\t\t\t<span class=\"pp-post-date\">\n\t\t\t\t\t\t<span class=\"pp-meta-text\">\n\t\t\t\tmayo 8, 2026\t\t\t<\/span>\n\t\t<\/span>\n\t\t<span class=\"pp-meta-separator\"><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"pp-post-wrap pp-grid-item-wrap elementor-grid-item post-55362 blog type-blog status-publish has-post-thumbnail hentry category-equipment-info\">\n\t\t\t\t\t\t<div class=\"pp-post pp-grid-item\">\n\t\t\t\t<div class=\"pp-post-content pp-content-always\">\n\t\t\t\t\t\t\t<div class=\"pp-post-thumbnail\">\n\t\t\t<a class=\"pp-post-thumbnail-wrap\" href=\"https:\/\/www.minejxsc.com\/es\/blog\/spiral-concentrator-low-cost-green-gravity-separator\/\" title=\"Spiral Concentrator: Low-Cost &amp; Green Gravity Separator\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2026\/04\/Spiral-concentrator.jpg\" class=\"attachment-large size-large wp-image-55363\" alt=\"Spiral concentrator\" srcset=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2026\/04\/Spiral-concentrator.jpg 1024w, https:\/\/www.minejxsc.com\/wp-content\/uploads\/2026\/04\/Spiral-concentrator-16x12.jpg 16w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"pp-image-overlay\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"pp-post-thumb-content-wrap\">\n\t\t\t\t\t\t<div class=\"pp-post-thumb-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"pp-post-title\">\n\t\t\t\t<a href=\"https:\/\/www.minejxsc.com\/es\/blog\/spiral-concentrator-low-cost-green-gravity-separator\/\" target=\"_blank\">Spiral Concentrator: Low-Cost &amp; Green Gravity Separator<\/a>\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t<div class=\"pp-post-meta\">\n\t\t\t\t\t\t\t\t<span class=\"pp-post-date\">\n\t\t\t\t\t\t<span class=\"pp-meta-text\">\n\t\t\t\tabril 28, 2026\t\t\t<\/span>\n\t\t<\/span>\n\t\t<span class=\"pp-meta-separator\"><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"pp-post-wrap pp-grid-item-wrap elementor-grid-item post-55262 blog type-blog status-publish has-post-thumbnail hentry category-mineral-solution\">\n\t\t\t\t\t\t<div class=\"pp-post pp-grid-item\">\n\t\t\t\t<div class=\"pp-post-content pp-content-always\">\n\t\t\t\t\t\t\t<div class=\"pp-post-thumbnail\">\n\t\t\t<a class=\"pp-post-thumbnail-wrap\" href=\"https:\/\/www.minejxsc.com\/es\/blog\/unlocking-high-grade-copper-the-power-of-ore-concentration\/\" title=\"Unlocking High-Grade Copper: The Power Of Ore Concentration\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2026\/04\/Unlocking-High-Grade-Copper-Ore-Concentration.jpg\" class=\"attachment-large size-large wp-image-55263\" alt=\"Unlocking High Grade Copper Ore Concentration\" srcset=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2026\/04\/Unlocking-High-Grade-Copper-Ore-Concentration.jpg 1024w, https:\/\/www.minejxsc.com\/wp-content\/uploads\/2026\/04\/Unlocking-High-Grade-Copper-Ore-Concentration-16x12.jpg 16w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"pp-image-overlay\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"pp-post-thumb-content-wrap\">\n\t\t\t\t\t\t<div class=\"pp-post-thumb-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"pp-post-title\">\n\t\t\t\t<a href=\"https:\/\/www.minejxsc.com\/es\/blog\/unlocking-high-grade-copper-the-power-of-ore-concentration\/\" target=\"_blank\">Unlocking High-Grade Copper: The Power Of Ore Concentration<\/a>\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t<div class=\"pp-post-meta\">\n\t\t\t\t\t\t\t\t<span class=\"pp-post-date\">\n\t\t\t\t\t\t<span class=\"pp-meta-text\">\n\t\t\t\tabril 20, 2026\t\t\t<\/span>\n\t\t<\/span>\n\t\t<span class=\"pp-meta-separator\"><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"pp-post-wrap pp-grid-item-wrap elementor-grid-item post-55201 blog type-blog status-publish has-post-thumbnail hentry category-equipment-info\">\n\t\t\t\t\t\t<div class=\"pp-post pp-grid-item\">\n\t\t\t\t<div class=\"pp-post-content pp-content-always\">\n\t\t\t\t\t\t\t<div class=\"pp-post-thumbnail\">\n\t\t\t<a class=\"pp-post-thumbnail-wrap\" href=\"https:\/\/www.minejxsc.com\/es\/blog\/impact-crusher-vs-cone-crusher-which-is-best-for-aggregates\/\" title=\"Impact Crusher Vs. Cone Crusher: Which Is Best For Aggregates?\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2026\/04\/Impact-Crusher-vs.-Cone-Crusher.jpg\" class=\"attachment-large size-large wp-image-55203\" alt=\"Impact Crusher vs. Cone Crusher\" srcset=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2026\/04\/Impact-Crusher-vs.-Cone-Crusher.jpg 1024w, https:\/\/www.minejxsc.com\/wp-content\/uploads\/2026\/04\/Impact-Crusher-vs.-Cone-Crusher-16x12.jpg 16w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"pp-image-overlay\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"pp-post-thumb-content-wrap\">\n\t\t\t\t\t\t<div class=\"pp-post-thumb-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"pp-post-title\">\n\t\t\t\t<a href=\"https:\/\/www.minejxsc.com\/es\/blog\/impact-crusher-vs-cone-crusher-which-is-best-for-aggregates\/\" target=\"_blank\">Impact Crusher Vs. Cone Crusher: Which Is Best For Aggregates?<\/a>\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t<div class=\"pp-post-meta\">\n\t\t\t\t\t\t\t\t<span class=\"pp-post-date\">\n\t\t\t\t\t\t<span class=\"pp-meta-text\">\n\t\t\t\tabril 14, 2026\t\t\t<\/span>\n\t\t<\/span>\n\t\t<span class=\"pp-meta-separator\"><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"pp-screen-only elementor-screen-only\" aria-live=\"polite\" id=\"pp-post-carousel-status\">Showing Slide 1 of 5<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>La miner\u00eda del oro consiste en extraer oro de la tierra a partir de su mineral. Para ello se utilizan diversos m\u00e9todos, todos ellos espec\u00edficos seg\u00fan las condiciones geol\u00f3gicas y la escala de la operaci\u00f3n. El oro se considera un metal precioso.<\/p>","protected":false},"featured_media":9573,"template":"","categories":[19],"tags":[],"class_list":["post-11587","blog","type-blog","status-publish","has-post-thumbnail","hentry","category-mineral-solution"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>what-type-of-mining-was-used-to-find-gold? - JXSC<\/title>\n<meta name=\"description\" content=\"Unravel the mystery of what type of mining was used to find gold throughout history. Explore the techniques on our blog.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.minejxsc.com\/es\/blog\/what-type-of-mining-was-used-to-find-gold\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"what-type-of-mining-was-used-to-find-gold? - JXSC\" \/>\n<meta property=\"og:description\" content=\"Unravel the mystery of what type of mining was used to find gold throughout history. Explore the techniques on our blog.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.minejxsc.com\/es\/blog\/what-type-of-mining-was-used-to-find-gold\/\" \/>\n<meta property=\"og:site_name\" content=\"JXSC\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-02T06:26:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/03\/secondary-crushing-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.minejxsc.com\\\/ru\\\/blog\\\/what-type-of-mining-was-used-to-find-gold\\\/\",\"url\":\"https:\\\/\\\/www.minejxsc.com\\\/ru\\\/blog\\\/what-type-of-mining-was-used-to-find-gold\\\/\",\"name\":\"what-type-of-mining-was-used-to-find-gold? - JXSC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.minejxsc.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.minejxsc.com\\\/ru\\\/blog\\\/what-type-of-mining-was-used-to-find-gold\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.minejxsc.com\\\/ru\\\/blog\\\/what-type-of-mining-was-used-to-find-gold\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.minejxsc.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/secondary-crushing-1.webp\",\"datePublished\":\"2024-08-01T02:18:23+00:00\",\"dateModified\":\"2024-08-02T06:26:19+00:00\",\"description\":\"Unravel the mystery of what type of mining was used to find gold throughout history. Explore the techniques on our blog.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.minejxsc.com\\\/ru\\\/blog\\\/what-type-of-mining-was-used-to-find-gold\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.minejxsc.com\\\/ru\\\/blog\\\/what-type-of-mining-was-used-to-find-gold\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.minejxsc.com\\\/ru\\\/blog\\\/what-type-of-mining-was-used-to-find-gold\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.minejxsc.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/secondary-crushing-1.webp\",\"contentUrl\":\"https:\\\/\\\/www.minejxsc.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/secondary-crushing-1.webp\",\"width\":1024,\"height\":768,\"caption\":\"gold\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.minejxsc.com\\\/ru\\\/blog\\\/what-type-of-mining-was-used-to-find-gold\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.minejxsc.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"What Type of Mining Was Used to Find Gold? An In-Depth Look\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.minejxsc.com\\\/#website\",\"url\":\"https:\\\/\\\/www.minejxsc.com\\\/\",\"name\":\"JXSC\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.minejxsc.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.minejxsc.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.minejxsc.com\\\/#organization\",\"name\":\"JXSC\",\"url\":\"https:\\\/\\\/www.minejxsc.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.minejxsc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.minejxsc.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/JXSC-LOGO-light.png\",\"contentUrl\":\"https:\\\/\\\/www.minejxsc.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/JXSC-LOGO-light.png\",\"width\":210,\"height\":50,\"caption\":\"JXSC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.minejxsc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfqu\u00e9 tipo de miner\u00eda se utiliz\u00f3 para extraer oro? - JXSC","description":"Desvele el misterio de qu\u00e9 tipo de miner\u00eda se utiliz\u00f3 para encontrar oro a lo largo de la historia. Explora las t\u00e9cnicas en nuestro blog.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.minejxsc.com\/es\/blog\/what-type-of-mining-was-used-to-find-gold\/","og_locale":"es_ES","og_type":"article","og_title":"what-type-of-mining-was-used-to-find-gold? - JXSC","og_description":"Unravel the mystery of what type of mining was used to find gold throughout history. Explore the techniques on our blog.","og_url":"https:\/\/www.minejxsc.com\/es\/blog\/what-type-of-mining-was-used-to-find-gold\/","og_site_name":"JXSC","article_modified_time":"2024-08-02T06:26:19+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/03\/secondary-crushing-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.minejxsc.com\/ru\/blog\/what-type-of-mining-was-used-to-find-gold\/","url":"https:\/\/www.minejxsc.com\/ru\/blog\/what-type-of-mining-was-used-to-find-gold\/","name":"\u00bfqu\u00e9 tipo de miner\u00eda se utiliz\u00f3 para extraer oro? - JXSC","isPartOf":{"@id":"https:\/\/www.minejxsc.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.minejxsc.com\/ru\/blog\/what-type-of-mining-was-used-to-find-gold\/#primaryimage"},"image":{"@id":"https:\/\/www.minejxsc.com\/ru\/blog\/what-type-of-mining-was-used-to-find-gold\/#primaryimage"},"thumbnailUrl":"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/03\/secondary-crushing-1.webp","datePublished":"2024-08-01T02:18:23+00:00","dateModified":"2024-08-02T06:26:19+00:00","description":"Desvele el misterio de qu\u00e9 tipo de miner\u00eda se utiliz\u00f3 para encontrar oro a lo largo de la historia. Explora las t\u00e9cnicas en nuestro blog.","breadcrumb":{"@id":"https:\/\/www.minejxsc.com\/ru\/blog\/what-type-of-mining-was-used-to-find-gold\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.minejxsc.com\/ru\/blog\/what-type-of-mining-was-used-to-find-gold\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.minejxsc.com\/ru\/blog\/what-type-of-mining-was-used-to-find-gold\/#primaryimage","url":"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/03\/secondary-crushing-1.webp","contentUrl":"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/03\/secondary-crushing-1.webp","width":1024,"height":768,"caption":"gold"},{"@type":"BreadcrumbList","@id":"https:\/\/www.minejxsc.com\/ru\/blog\/what-type-of-mining-was-used-to-find-gold\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.minejxsc.com\/"},{"@type":"ListItem","position":2,"name":"What Type of Mining Was Used to Find Gold? An In-Depth Look"}]},{"@type":"WebSite","@id":"https:\/\/www.minejxsc.com\/#website","url":"https:\/\/www.minejxsc.com\/","name":"JXSC","description":"","publisher":{"@id":"https:\/\/www.minejxsc.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.minejxsc.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.minejxsc.com\/#organization","name":"JXSC","url":"https:\/\/www.minejxsc.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.minejxsc.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2022\/10\/JXSC-LOGO-light.png","contentUrl":"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2022\/10\/JXSC-LOGO-light.png","width":210,"height":50,"caption":"JXSC"},"image":{"@id":"https:\/\/www.minejxsc.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.minejxsc.com\/es\/wp-json\/wp\/v2\/blog\/11587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.minejxsc.com\/es\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/www.minejxsc.com\/es\/wp-json\/wp\/v2\/types\/blog"}],"version-history":[{"count":0,"href":"https:\/\/www.minejxsc.com\/es\/wp-json\/wp\/v2\/blog\/11587\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.minejxsc.com\/es\/wp-json\/wp\/v2\/media\/9573"}],"wp:attachment":[{"href":"https:\/\/www.minejxsc.com\/es\/wp-json\/wp\/v2\/media?parent=11587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.minejxsc.com\/es\/wp-json\/wp\/v2\/categories?post=11587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.minejxsc.com\/es\/wp-json\/wp\/v2\/tags?post=11587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}