{"id":10508,"date":"2024-06-11T09:36:32","date_gmt":"2024-06-11T01:36:32","guid":{"rendered":"https:\/\/www.minejxsc.com\/?post_type=blog&#038;p=10508"},"modified":"2025-03-17T10:58:00","modified_gmt":"2025-03-17T02:58:00","slug":"how-is-gold-formed","status":"publish","type":"blog","link":"https:\/\/www.minejxsc.com\/es\/blog\/how-is-gold-formed\/","title":{"rendered":"C\u00f3mo se forma el oro: Explorando el viaje del espacio a la Tierra"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"10508\" class=\"elementor elementor-10508\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"blog\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-efd1a27 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"efd1a27\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e6a049c\" data-id=\"e6a049c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f08560 elementor-widget elementor-widget-pp-breadcrumbs\" data-id=\"5f08560\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;breadcrumbs_type&quot;:&quot;powerpack&quot;}\" data-widget_type=\"pp-breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"pp-breadcrumbs pp-breadcrumbs-powerpack\">\t\t<li class=\"pp-breadcrumbs-item pp-breadcrumbs-item-home\">\n\t\t\t<a class=\"pp-breadcrumbs-crumb pp-breadcrumbs-crumb-link pp-breadcrumbs-crumb-home\" href=\"https:\/\/www.minejxsc.com\/es\" title=\"Inicio\">\n\t\t\t\t<span class=\"pp-breadcrumbs-text\">\n\t\t\t\t\t\t\t\t\t\tInicio\t\t\t\t<\/span>\n\t\t\t<\/a>\n\t\t<\/li>\n\t\t<li class=\"pp-breadcrumbs-separator\">\t\t\t\t<span class='pp-separator-icon pp-icon'>\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t\t<\/li><\/ul>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-55b3982 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"55b3982\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-53ac0b3\" data-id=\"53ac0b3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-adc28d8 ha-has-bg-overlay elementor-widget elementor-widget-post-navigation\" data-id=\"adc28d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-navigation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-post-navigation\" role=\"navigation\" aria-label=\"Navegaci\u00f3n de la entrada\">\n\t\t\t<div class=\"elementor-post-navigation__prev elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/www.minejxsc.com\/es\/blog\/4-types-of-iron-ore\/\" rel=\"prev\"><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-prev\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-left\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.7 239l136-136c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9L127.9 256l96.4 96.4c9.4 9.4 9.4 24.6 0 33.9L201.7 409c-9.4 9.4-24.6 9.4-33.9 0l-136-136c-9.5-9.4-9.5-24.6-.1-34z\"><\/path><\/svg><span class=\"elementor-screen-only\">Ant<\/span><\/span><span class=\"elementor-post-navigation__link__prev\"><span class=\"post-navigation__prev--label\">Anterior<\/span><span class=\"post-navigation__prev--title\">Gu\u00eda completa de los 4 tipos de mineral de hierro<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-post-navigation__next elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/www.minejxsc.com\/es\/blog\/how-to-identify-gold-ore\/\" rel=\"next\"><span class=\"elementor-post-navigation__link__next\"><span class=\"post-navigation__next--label\">Siguiente<\/span><span class=\"post-navigation__next--title\">Los mejores m\u00e9todos para identificar mineral de oro en el campo<\/span><\/span><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-next\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><span class=\"elementor-screen-only\">Siguiente<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-136e3fb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"136e3fb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1228be6\" data-id=\"1228be6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc07a38 elementor-widget elementor-widget-post-info\" data-id=\"fc07a38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-c57f942 elementor-inline-item\" itemprop=\"author\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-user-circle\" viewbox=\"0 0 496 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M248 104c-53 0-96 43-96 96s43 96 96 96 96-43 96-96-43-96-96-96zm0 144c-26.5 0-48-21.5-48-48s21.5-48 48-48 48 21.5 48 48-21.5 48-48 48zm0-240C111 8 0 119 0 256s111 248 248 248 248-111 248-248S385 8 248 8zm0 448c-49.7 0-95.1-18.3-130.1-48.4 14.9-23 40.4-38.6 69.6-39.5 20.8 6.4 40.6 9.6 60.5 9.6s39.7-3.1 60.5-9.6c29.2 1 54.7 16.5 69.6 39.5-35 30.1-80.4 48.4-130.1 48.4zm162.7-84.1c-24.4-31.4-62.1-51.9-105.1-51.9-10.2 0-26 9.6-57.6 9.6-31.5 0-47.4-9.6-57.6-9.6-42.9 0-80.6 20.5-105.1 51.9C61.9 339.2 48 299.2 48 256c0-110.3 89.7-200 200-200s200 89.7 200 200c0 43.2-13.9 83.2-37.3 115.9z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-author\">\n\t\t\t\t\t\t\t\t\t\tminejxsc\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-d73c698 elementor-inline-item\" itemprop=\"datePublished\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-calendar\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M12 192h424c6.6 0 12 5.4 12 12v260c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V204c0-6.6 5.4-12 12-12zm436-44v-36c0-26.5-21.5-48-48-48h-48V12c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v52H160V12c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v52H48C21.5 64 0 85.5 0 112v36c0 6.6 5.4 12 12 12h424c6.6 0 12-5.4 12-12z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-date\">\n\t\t\t\t\t\t\t\t\t\t<time>11 de junio de 2024<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-24f5706 elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-clock\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm0 448c-110.5 0-200-89.5-200-200S145.5 56 256 56s200 89.5 200 200-89.5 200-200 200zm61.8-104.4l-84.9-61.7c-3.1-2.3-4.9-5.9-4.9-9.7V116c0-6.6 5.4-12 12-12h32c6.6 0 12 5.4 12 12v141.7l66.8 48.6c5.4 3.9 6.5 11.4 2.6 16.8L334.6 349c-3.9 5.3-11.4 6.5-16.8 2.6z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-time\">\n\t\t\t\t\t\t\t\t\t\t<time>9:36 horas<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73768bb elementor-widget elementor-widget-heading\" data-id=\"73768bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfQu\u00e9 es el oro?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6a9ca8 elementor-widget elementor-widget-image\" data-id=\"a6a9ca8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/06\/gold1\uff09.webp\" class=\"attachment-medium size-medium wp-image-10449\" alt=\"oro(1\uff09\" srcset=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/06\/gold1\uff09.webp 1024w, https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/06\/gold1\uff09-600x450.webp 600w, https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/06\/gold1\uff09-768x576.webp 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35c9125 elementor-widget elementor-widget-text-editor\" data-id=\"35c9125\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div data-page-id=\"LEwVdOpQAoSfLRxrffecbhMwnnh\" data-docx-has-block-data=\"false\"><div class=\"ace-line ace-line old-record-id-WU5edi4GwoTxFbxuzMEcrlIPn7c\">El oro es un metal de transici\u00f3n con el s\u00edmbolo Au, derivado de la palabra latina para oro, Aurum, y el n\u00famero at\u00f3mico 79 en la tabla peri\u00f3dica. El oro es un elemento qu\u00edmico, un metal amarillo brillante con un lustroso brillo y es uno de los elementos qu\u00edmicamente m\u00e1s inactivos, por lo que es muy resistente a la corrosi\u00f3n y la oxidaci\u00f3n. Este metal precioso es muy denso, buen conductor de la electricidad y muy d\u00factil, lo que significa que se puede doblar o enrollar en diferentes formas sin que se agriete.<\/div><div>\u00a0<\/div><div class=\"ace-line ace-line old-record-id-DatDdjo3cobddvxz1GMcthtgntc\">El oro se ha utilizado con diversos fines a lo largo de la historia de la humanidad. Debido a su escasez y a sus caracter\u00edsticas especiales, se ha asociado con el prestigio y la riqueza, y se ha utilizado en la acu\u00f1aci\u00f3n de monedas, adornos de oro y lingotes de oro. Estas caracter\u00edsticas del oro lo hacen ideal para su uso en electr\u00f3nica y odontolog\u00eda debido a sus propiedades f\u00edsicas. Se utiliza en naves espaciales y aplicaciones de alta tecnolog\u00eda por sus caracter\u00edsticas reflectantes.<\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74e040b elementor-widget elementor-widget-heading\" data-id=\"74e040b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Oro frente a otros metales preciosos<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-556f7e7 elementor-widget__width-initial pp-table-center elementor-widget elementor-widget-pp-table\" data-id=\"556f7e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;table_type&quot;:&quot;responsive&quot;,&quot;scrollable&quot;:&quot;no&quot;}\" data-widget_type=\"pp-table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"pp-table-container\">\n\t\t\t<table \n\t\t\tclass=\"pp-table tablesaw\" data-tablesaw-mode=\"stack\"\t\t\t\t>\n\t\t\t\t\t\t\t<colgroup>\n\t\t\t\t\t\t\t\t<col\n\t\t\t\t\tspan=\"1\"\n\t\t\t\t\tclass=\"elementor-repeater-item-32d7a45\"\n\t\t\t\t\t\t\t\t\t\t\tstyle=\"\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\"\n\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t<\/colgroup>\n\t\t\t\t\t\t<thead>\n\t\t\t\t<tr class=\"pp-table-row\">\n\t\t\t\t\t<th class=\"pp-table-cell pp-table-cell-8cf5bb8\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Caracter\u00edstica<\/span><\/span><\/th><th class=\"pp-table-cell pp-table-cell-061a599\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Oro<\/span><\/span><\/th><th class=\"pp-table-cell pp-table-cell-0b07b05\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Plata\t<\/span><\/span><\/th><th class=\"pp-table-cell pp-table-cell-d2630c2\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Platino\t<\/span><\/span><\/th><th class=\"pp-table-cell pp-table-cell-cd20e4c\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Paladio<\/span><\/span><\/th>\t\t\t\t<\/tr>\n\t\t\t<\/thead>\n\t\t\t\t\t<tfoot>\n\t\t\t<\/tr>\t\t<\/tfoot>\n\t\t\t\t<tbody>\n\t\t\t<tr ><td class=\"pp-table-cell pp-table-cell-524b949\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">S\u00edmbolo qu\u00edmico<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-eb9c69c\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">AU<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-495d9d4\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Ag<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-b22451b\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Pt<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-aa48438\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Pd<\/span><\/span><\/td><\/tr><tr ><td class=\"pp-table-cell pp-table-cell-8b9591a\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">N\u00famero at\u00f3mico<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-8f39f58\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">79<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-b7f630f\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">47<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-c52e49f\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">78<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-a244ff7\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">46<\/span><\/span><\/td><\/tr><tr ><td class=\"pp-table-cell pp-table-cell-ca30337\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Color\t<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-f87fcd7\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Amarillo\t<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-051e909\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Blanco\/Gris\t<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-1d75191\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Blanco plateado<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-c558be2\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Blanco plateado<\/span><\/span><\/td><\/tr><tr ><td class=\"pp-table-cell pp-table-cell-5a75982\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Densidad (g\/cm\u00b3)\t<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-3bc7156\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">19.3\t<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-146f7e1\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">10.5\t<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-6476467\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">21.45\t<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-476e8b1\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">12.02<\/span><\/span><\/td><\/tr><tr ><td class=\"pp-table-cell pp-table-cell-bd67e35\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Maleabilidad<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-4bf49fe\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Extremadamente maleable, puede martillearse en l\u00e1minas finas sin romperse<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-c909da0\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Muy maleable, pero menos que el oro, puede deslustrarse<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-ae6b425\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Muy maleable, no se empa\u00f1a<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-b0d7ac9\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Maleable, pero menos que el oro y el platino, resistente a la corrosi\u00f3n<\/span><\/span><\/td><\/tr><tr ><td class=\"pp-table-cell pp-table-cell-a0ff90b\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Conductividad el\u00e9ctrica<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-80bbe87\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Excelente. Muy utilizado en conectores y circuitos electr\u00f3nicos<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-da9bd04\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Excelente, utilizado en electr\u00f3nica y espejos<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-a6f026d\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Bueno, utilizado en catalizadores y electr\u00f3nica<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-87c4a0a\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Bueno, tambi\u00e9n se utiliza en catalizadores y electr\u00f3nica<\/span><\/span><\/td><\/tr><tr ><td class=\"pp-table-cell pp-table-cell-38ee31c\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Usos principales<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-e6c7365\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Joyer\u00eda, electr\u00f3nica, monedas, aplicaciones dentales, aeroespacial<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-9894987\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Joyer\u00eda, electr\u00f3nica, monedas, aplicaciones industriales<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-969667c\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Joyer\u00eda, aplicaciones industriales, equipos m\u00e9dicos<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-33e916a\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Electr\u00f3nica, catalizadores, joyer\u00eda<\/span><\/span><\/td><\/tr><tr ><td class=\"pp-table-cell pp-table-cell-75e7a53\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Valor econ\u00f3mico (por oz)<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-953a002\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Muy alta. Impulsado por la rareza y la demanda en m\u00faltiples industrias.<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-d606f6e\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Moderado, muy utilizado pero m\u00e1s abundante que el oro<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-997d4bc\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Muy alto, m\u00e1s raro que el oro, utilizado en aplicaciones especializadas<\/span><\/span><\/td><td class=\"pp-table-cell pp-table-cell-74d40be\"><span class=\"pp-table-cell-content\"><span class=\"pp-table-cell-text\">Alto, valioso para usos industriales y electr\u00f3nicos<\/span><\/span><\/td><\/tr>\t\t<\/tbody>\n\t\t\t\t\t<\/table>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd2795d elementor-widget elementor-widget-heading\" data-id=\"bd2795d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfDe d\u00f3nde procede el oro?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9deece9 elementor-widget elementor-widget-image\" data-id=\"9deece9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/06\/Gold-Originate.webp\" class=\"attachment-medium size-medium wp-image-10451\" alt=\"Origen del oro\" srcset=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/06\/Gold-Originate.webp 1024w, https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/06\/Gold-Originate-600x450.webp 600w, https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/06\/Gold-Originate-768x576.webp 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7cdd23 elementor-widget elementor-widget-text-editor\" data-id=\"d7cdd23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El origen del oro puede rastrearse hasta los rincones m\u00e1s lejanos del universo, m\u00e1s all\u00e1 de nuestro sistema solar. Para comprender el origen del oro es necesario investigar los fen\u00f3menos astron\u00f3micos que se producen y las condiciones geol\u00f3gicas de la Tierra.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e31de25 elementor-widget elementor-widget-heading\" data-id=\"e31de25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Or\u00edgenes astron\u00f3micos del oro<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-713defa elementor-widget elementor-widget-text-editor\" data-id=\"713defa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div data-page-id=\"LEwVdOpQAoSfLRxrffecbhMwnnh\" data-docx-has-block-data=\"false\">\n<h4 class=\"heading-3 ace-line old-record-id-RnFQdjD8mo7hWMxD2Xbc47TenXf\"><span style=\"color: rgb(146, 151, 164); font-size: 14px; font-weight: 400; text-transform: none;\">El origen del oro tiene lugar en las estrellas. Los elementos pesados, como el oro, se sintetizan mediante nucleos\u00edntesis en las violentas condiciones de las supernovas y las fusiones de estrellas de neutrones.<\/span><br><\/h4>\n<div>&nbsp;<\/div>\n<div class=\"ace-line ace-line old-record-id-ZAx5d5XhQofchvxEccfc5yPtnXc\">La nucleos\u00edntesis de las supernovas se produce cuando una estrella masiva colapsa al final de su ciclo vital, provocando temperaturas y presiones extremadamente altas que pueden permitir la creaci\u00f3n de elementos m\u00e1s pesados mediante la fusi\u00f3n con otros m\u00e1s ligeros. Estas poderosas explosiones dispersan \u00e1tomos de oro por todo el espacio.Las ondas gravitatorias y la enorme energ\u00eda resultantes de la colisi\u00f3n de estrellas de neutrones producen elementos pesados como el oro. Aunque ocurren con poca frecuencia, estos acontecimientos son inmensamente poderosos y contribuyen a la prevalencia del oro en este universo.<\/div>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-faef19b elementor-widget elementor-widget-heading\" data-id=\"faef19b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Condiciones geol\u00f3gicas del dep\u00f3sito de oro<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6811d1e elementor-widget elementor-widget-text-editor\" data-id=\"6811d1e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El oro se deposita en la Tierra en determinadas condiciones geol\u00f3gicas, a menudo como resultado de actividades tect\u00f3nicas e hidrotermales. Diferentes tipos de minerales, entre ellos el oro, son tra\u00eddos a la corteza por la roca fundida que asciende desde el manto. Cuando este magma se enfr\u00eda y solidifica, puede atrapar el oro en vetas de cuarzo y otras formaciones rocosas.<\/p><p><br \/>Los procesos relacionados con las soluciones calientes son muy importantes en la deposici\u00f3n del oro. El oro, junto con otros tipos de minerales, es transportado por estas soluciones calientes ricas en fluidos al reaccionar con las rocas circundantes enfri\u00e1ndose a lo largo de fracturas y grietas dentro de la corteza terrestre. Estos procesos suelen producirse en zonas de intensa actividad volc\u00e1nica, ya que en ellas se dan las mejores condiciones para la formaci\u00f3n de minerales ricos por naturaleza. A lo largo de millones de a\u00f1os, estas condiciones geol\u00f3gicas han desempe\u00f1ado un papel importante en la concentraci\u00f3n de yacimientos de oro econ\u00f3micamente viables, como los que se encuentran en la cuenca sudafricana de Witwatersrand, as\u00ed como en dep\u00f3sitos aluviales en lechos de arroyos y llanuras aluviales.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a08d37f elementor-widget elementor-widget-heading\" data-id=\"a08d37f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfC\u00f3mo se forma el oro?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff35db8 elementor-widget elementor-widget-text-editor\" data-id=\"ff35db8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Para comprender c\u00f3mo se forma el oro, hay que tener en cuenta los factores c\u00f3smicos y geol\u00f3gicos que han influido en la distribuci\u00f3n y disponibilidad del metal.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-574d2ff elementor-widget elementor-widget-heading\" data-id=\"574d2ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Procesos astrof\u00edsicos<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89cf74c elementor-widget elementor-widget-text-editor\" data-id=\"89cf74c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div data-page-id=\"LEwVdOpQAoSfLRxrffecbhMwnnh\" data-docx-has-block-data=\"false\"><div class=\"ace-line ace-line old-record-id-PCrSdyw0foZLMGxcvIxce7tvngb\"><strong>Supernova<\/strong><\/div><div class=\"ace-line ace-line old-record-id-UrRfdEp8poyDX0x4VbrcJ5fenTd\">El oro se forma principalmente en las secuelas explosivas de una supernova, una de las explosiones m\u00e1s potentes del universo. Las estrellas masivas se quedan sin combustible nuclear y se colapsan antes de explotar. Estas explosiones generan temperaturas y presiones tan elevadas que favorecen las reacciones at\u00f3micas que crean elementos pesados como el oro. La energ\u00eda de la explosi\u00f3n dispersa estos \u00e1tomos de oro reci\u00e9n formados por todo el espacio, suministrando metales valiosos al medio interestelar circundante. En \u00faltima instancia, se encuentran entre los \u00e1tomos de oro dispersos que m\u00e1s tarde se asimilan al polvo c\u00f3smico que constituye nuevas estrellas, planetas y otros cuerpos celestes.<\/div><div>\u00a0<\/div><div class=\"ace-line ace-line old-record-id-W5y5dQFPFoT2JZxmHEfcqaRlnCe\"><strong>Neutr\u00f3n<\/strong><strong> Colisiones estelares<\/strong><\/div><div class=\"ace-line ace-line old-record-id-YLXXdq1EyoAHwgxSTowcKU32nsh\">Otro importante proceso astrof\u00edsico que contribuye a la formaci\u00f3n del oro es la colisi\u00f3n de estrellas de neutrones. Cuando dos estrellas de neutrones, restos de supernovas que han sufrido un colapso gravitatorio, se juntan girando una alrededor de la otra hasta colisionar, producen una enorme cantidad de energ\u00eda. Esta violenta colisi\u00f3n crea condiciones a\u00fan m\u00e1s extremas que las de una supernova, dando lugar a una r\u00e1pida captura de neutrones por n\u00facleos at\u00f3micos, un proceso conocido como nucleos\u00edntesis del proceso r. Este proceso produce abundantes elementos pesados, entre ellos el oro. El oro expulsado de tales colisiones se suma a lo que ya exist\u00eda de este metal en el universo.<\/div><div>\u00a0<\/div><div class=\"ace-line ace-line old-record-id-XGrydVz7QogVUyxDaRfcvayvnpc\"><strong>Polvo c\u00f3smico<\/strong><\/div><div class=\"ace-line ace-line old-record-id-JoGBdg35aoKRTexCXLpcpUzQnw5\">El polvo c\u00f3smico, que es un polvo fino procedente de estrellas y otros objetos celestes, tambi\u00e9n interviene en la creaci\u00f3n del oro. En acontecimientos como las supernovas y las colisiones de estrellas de neutrones, se produce una gran cantidad de energ\u00eda y los elementos m\u00e1s ligeros se combinan para formar elementos m\u00e1s pesados como el oro. Estos \u00e1tomos de oro reci\u00e9n formados son expulsados al espacio y pasan a formar parte del polvo c\u00f3smico presente en el universo actual. Este polvo aur\u00edfero se acumula poco a poco y se convierte en el material que crea nuevas estrellas y sistemas planetarios.<\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db7ed5f elementor-widget elementor-widget-heading\" data-id=\"db7ed5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Procesos geol\u00f3gicos de la Tierra<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-361a2db elementor-widget elementor-widget-text-editor\" data-id=\"361a2db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div data-page-id=\"LEwVdOpQAoSfLRxrffecbhMwnnh\" data-docx-has-block-data=\"false\"><div class=\"ace-line ace-line old-record-id-WGHidxbUXoFWaDxHCoxcPc3incg\"><div data-page-id=\"LEwVdOpQAoSfLRxrffecbhMwnnh\" data-docx-has-block-data=\"false\"><div class=\"ace-line ace-line old-record-id-REfrd4Pb2o7Ro6xm3uPc9mFfndg\"><strong>Actividad hidrotermal<\/strong><\/div><div class=\"ace-line ace-line old-record-id-WGHidxbUXoFWaDxHCoxcPc3incg\">El proceso hidrotermal es uno de los m\u00e1s importantes en la formaci\u00f3n de yacimientos de oro en nuestro planeta. Supone la circulaci\u00f3n de fluidos calientes y mineralizados en la corteza terrestre a trav\u00e9s de grietas y fisuras. Estos fluidos proceden de fuentes magm\u00e1ticas del manto terrestre y transportan oro disuelto junto con otras especies. Los fluidos hidrotermales ascienden por las rocas porosas y, al entrar en contacto con la superficie, se enfr\u00edan y depositan el oro de la soluci\u00f3n en forma de minerales s\u00f3lidos. Esto es especialmente com\u00fan en zonas con gran actividad volc\u00e1nica porque el calor y la presi\u00f3n son perfectos para los sistemas hidrotermales. El producto final es la formaci\u00f3n de vetas de cuarzo que contienen oro y que pueden explotarse por su contenido en el metal precioso. Algunos de los yacimientos de oro m\u00e1s ricos del mundo, como los de Estados Unidos y Sud\u00e1frica, est\u00e1n asociados a la actividad hidrotermal.<\/div><div>\u00a0<\/div><div class=\"ace-line ace-line old-record-id-XEaWdZGiGomzrLxT2lDcQxSVnvf\"><strong>Yacimientos<\/strong><\/div><div class=\"ace-line ace-line old-record-id-WbMtdvURMorbt5x652xcAEJcnth\">Los yacimientos de placeres se crean cuando el oro se desprende de su material original y es transportado por el agua hasta un nuevo lugar donde se deposita en canales fluviales, gravas de arroyos o arenas costeras. A la larga, las part\u00edculas de oro m\u00e1s densas se hunden y acumulan en estos lugares debido a su densidad, dejando atr\u00e1s otros materiales como arena y grava. Estos yacimientos son relativamente m\u00e1s f\u00e1ciles de explotar que las fuentes de roca dura, ya que el oro puede recuperarse f\u00e1cilmente con m\u00e9todos como el bateo, el lavado y el dragado. Los dep\u00f3sitos aluviales han sido una de las fuentes m\u00e1s importantes de oro y han dado lugar a la formaci\u00f3n de fiebre del oro y a la producci\u00f3n de oro a gran escala en el mundo. Para entender c\u00f3mo estos dep\u00f3sitos se convierten en oro valioso, lea sobre la <a href=\"https:\/\/www.minejxsc.com\/es\/blog\/gold-mining-processes\/\">\"Comprender el proceso de extracci\u00f3n de oro: Una gu\u00eda completa\"<\/a>\u00a0<\/div><div>\u00a0<\/div><div class=\"ace-line ace-line old-record-id-OW9fd6X9BopBuExDJdPcYyt4nQd\"><strong>Entrega de meteoritos<\/strong><\/div><div class=\"ace-line ace-line old-record-id-OuoPdbkMBomPA8xQzNbcbXLunTd\">La superficie de la Tierra se ha visto muy afectada por los impactos de meteoritos que le han aportado oro. Cuando la Tierra se estaba formando, se produjo un intenso bombardeo del planeta por meteoritos y asteroides. Muchos de ellos estaban compuestos por elementos pesados como el oro. Su impacto en la Tierra provoc\u00f3 la deposici\u00f3n de su contenido met\u00e1lico en la corteza.<\/div><div>\u00a0<\/div><div class=\"ace-line ace-line old-record-id-PFAtdjAP0o1795xxk8EczX80n2g\">Este proceso ayud\u00f3 a distribuir el oro por la superficie terrestre, especialmente en zonas con altos \u00edndices de craterizaci\u00f3n por impacto. Sin embargo, los yacimientos de oro creados por el aporte meteor\u00edtico son relativamente raros en comparaci\u00f3n con los formados \u00fanicamente por procesos geol\u00f3gicos. El oro tra\u00eddo a la tierra hace millones de a\u00f1os por impactos se ha convertido en acumulaciones localizadas que posteriormente se han desplazado y transformado por acontecimientos geol\u00f3gicos posteriores. A pesar de su papel en el enriquecimiento de las reservas mundiales de oro, el transporte meteor\u00edtico no es la principal v\u00eda de formaci\u00f3n de este metal precioso en nuestro planeta.<\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b6b2d5 elementor-widget elementor-widget-heading\" data-id=\"4b6b2d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u00bfCu\u00e1l es la forma m\u00e1s f\u00e1cil de conseguir oro?<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4dded93 elementor-widget elementor-widget-text-editor\" data-id=\"4dded93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>De todos los procesos que tienen lugar en la Tierra y en el espacio, los procesos geol\u00f3gicos son los m\u00e1s convenientes y factibles para extraer oro en la Tierra. Las supernovas y las colisiones de estrellas de neutrones producen oro en el espacio, pero este oro est\u00e1 diseminado por todo el universo y no puede obtenerse f\u00e1cilmente. La entrega de meteoritos, aunque ha aumentado las reservas de oro de la Tierra, no deja el oro en una \u00fanica zona concentrada. En la Tierra, procesos geol\u00f3gicos como el hidrotermalismo concentran el oro en formas econ\u00f3micamente viables como las vetas de cuarzo y los placeres. Estas formaciones son m\u00e1s f\u00e1ciles de extraer y purificar, por lo que constituyen la principal fuente de oro para consumo humano.<\/p><p>\u00a0<\/p><p>Si busca soluciones eficaces para el tratamiento del oro, consulte nuestra completa <a href=\"https:\/\/www.minejxsc.com\/es\/mineral-processing-equipment\/\" target=\"_new\" rel=\"noreferrer\" data-immersive-translate-walked=\"db321e69-d2d6-42d7-8003-dfb85200e1b2\">equipos de tratamiento de minerales<\/a> recursos.<span class=\"notranslate immersive-translate-target-wrapper\" lang=\"zh-CN\" data-immersive-translate-translation-element-mark=\"1\"><br \/><\/span><\/p><p><span lang=\"zh-CN\" style=\"border: 0px solid #e3e3e3; --tw-border-spacing-x: 0; --tw-border-spacing-y: 0; --tw-translate-x: 0; --tw-translate-y: 0; --tw-rotate: 0; --tw-skew-x: 0; --tw-skew-y: 0; --tw-scale-x: 1; --tw-scale-y: 1; --tw-scroll-snap-strictness: proximity; --tw-ring-offset-width: 0px; --tw-ring-offset-color: #fff; --tw-ring-color: rgba(69,89,164,.5); --tw-ring-offset-shadow: 0 0 transparent; --tw-ring-shadow: 0 0 transparent; --tw-shadow: 0 0 transparent; --tw-shadow-colored: 0 0 transparent; word-break: break-word; color: #0d0d0d; font-family: ui-sans-serif, -apple-system, system-ui, 'Segoe UI', Roboto, Ubuntu, Cantarell, 'Noto Sans', sans-serif, Helvetica, 'Apple Color Emoji', Arial, 'Segoe UI Emoji', 'Segoe UI Symbol'; font-size: 16px; white-space-collapse: preserve; background-color: #ffffff;\" data-immersive-translate-translation-element-mark=\"1\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b46b80 elementor-widget elementor-widget-heading\" data-id=\"6b46b80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Inversi\u00f3n en oro y tendencias del mercado<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6ca1e7 elementor-widget elementor-widget-image\" data-id=\"a6ca1e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/06\/gold-2.webp\" class=\"attachment-medium size-medium wp-image-10452\" alt=\"oro (2)\" srcset=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/06\/gold-2.webp 1024w, https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/06\/gold-2-600x450.webp 600w, https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/06\/gold-2-768x576.webp 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44c7dec elementor-widget elementor-widget-text-editor\" data-id=\"44c7dec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Durante muchos a\u00f1os, el oro se ha considerado una materia prima importante para los inversores, ya que act\u00faa como una buena cobertura frente a la inflaci\u00f3n y el riesgo cambiario. Hoy en d\u00eda, la inversi\u00f3n en oro se ha convertido en una v\u00eda de inversi\u00f3n popular, especialmente debido a la inestabilidad de la econom\u00eda mundial y a las crisis pol\u00edticas. En cuanto al oro, su demanda est\u00e1 creciendo debido al deseo de los inversores de invertir en activos seguros, mientras que los precios son vol\u00e1tiles. La disponibilidad de fondos cotizados en bolsa (ETF) de oro y de plataformas digitales de oro tambi\u00e9n ha contribuido a la democratizaci\u00f3n de la inversi\u00f3n en oro.<\/p><p>\u00a0<\/p><p>En el futuro de la inversi\u00f3n en oro influir\u00e1n los siguientes factores: las fluctuaciones econ\u00f3micas, el desarrollo tecnol\u00f3gico y el creciente uso del oro en distintos sectores como la electr\u00f3nica y las energ\u00edas renovables. El oro seguir\u00e1 siendo una materia prima importante en las carteras financieras mundiales a medida que se creen nuevos mercados y se modifiquen los antiguos, debido al valor inherente del metal y a su utilidad en diversas aplicaciones.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc28352 elementor-widget elementor-widget-heading\" data-id=\"bc28352\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00bfD\u00f3nde se encuentra el oro en el mundo?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12f1075 elementor-widget elementor-widget-text-editor\" data-id=\"12f1075\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Los yacimientos de oro se encuentran en distintas partes del mundo y est\u00e1n relacionados con determinadas estructuras geol\u00f3gicas. Algunas de las zonas productoras de oro m\u00e1s notables son:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8aa4f9 elementor-widget elementor-widget-text-editor\" data-id=\"b8aa4f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div data-page-id=\"LEwVdOpQAoSfLRxrffecbhMwnnh\" data-docx-has-block-data=\"false\"><div class=\"ace-line ace-line old-record-id-G828dJ6bcoZ4VzxXhDlcq4qsnHb\"><strong>\u25cf Sud\u00e1frica: <\/strong>La cuenca de Witwatersrand, en Sud\u00e1frica, es una de las regiones aur\u00edferas m\u00e1s grandes y productivas del mundo.<\/div><div class=\"ace-line ace-line old-record-id-NvjpdPm2Bo2vTwx3qjrcAcQ5nfe\"><strong>\u25cf Estados Unidos: <\/strong>Estados Unidos est\u00e1 dotado de yacimientos de oro que se encuentran en lugares como Nevada, Alaska y California, entre otros. Estas regiones contienen grandes yacimientos de oro aluvial y de veta.<\/div><div class=\"ace-line ace-line old-record-id-WUJbdVBL5okeoHxTTAxcutfznMd\"><strong>\u25cf Australia:<\/strong> Australia es otro pa\u00eds que posee grandes reservas de oro, sobre todo en las regiones de Australia Occidental y Victoria, famosas por la extracci\u00f3n de oro a gran escala.<\/div><div class=\"ace-line ace-line old-record-id-Wr3pdPKyeoYM3OxLGBJcD19mnjX\"><strong>\u25cf China:<\/strong> China es el mayor productor de oro del mundo y cuenta con numerosas empresas mineras, sobre todo en las regiones de Shandong y Henan.<\/div><div class=\"ace-line ace-line old-record-id-NX06dE5wQojwU0xCMcycnpEEnof\"><strong>\u25cf Rusia: <\/strong>Rusia posee grandes reservas de oro en Siberia y Extremo Oriente, ya que es un pa\u00eds de recursos naturales.<\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3dc9827 elementor-widget elementor-widget-text-editor\" data-id=\"3dc9827\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Descubra las principales minas de oro <a href=\"https:\/\/www.minejxsc.com\/es\/blog\/the-largest-gold-mine-in-the-world\/\">Explore la mayor mina de oro del mundo: Las 10 mejores.<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4997a81 elementor-widget elementor-widget-heading\" data-id=\"4997a81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Conclusi\u00f3n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e05c97 elementor-widget elementor-widget-text-editor\" data-id=\"7e05c97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La futura extracci\u00f3n y creaci\u00f3n de oro pasa por el progreso en el conocimiento de las actividades de la Tierra y el espacio exterior y, al mismo tiempo, por la b\u00fasqueda de m\u00e9todos de extracci\u00f3n m\u00e1s sostenibles. La tecnolog\u00eda actual est\u00e1 conduciendo al descubrimiento de m\u00e9todos alternativos eficientes y respetuosos con el medio ambiente, como la biominer\u00eda y la qu\u00edmica verde, entre otros.<\/p><p>\u00a0<\/p><p>Adem\u00e1s, el desarrollo ayudar\u00e1 a reducir los da\u00f1os medioambientales causados por la extracci\u00f3n de oro, manteniendo al mismo tiempo la productividad econ\u00f3mica. Adem\u00e1s, a medida que los cient\u00edficos sigan estudiando c\u00f3mo surgi\u00f3 el oro y d\u00f3nde puede encontrarse, es posible que se desarrollen procesos mineros menos invasivos. Al fusionar el conocimiento cient\u00edfico con los avances t\u00e9cnicos modernos, la industria del oro parece estar preparada para encontrar un equilibrio entre la demanda mundial y la conservaci\u00f3n para la posteridad.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6245100 elementor-widget elementor-widget-heading\" data-id=\"6245100\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Asociarse con JXSC para extraer f\u00e1cilmente oro del mineral<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9c03a4 elementor-widget elementor-widget-text-editor\" data-id=\"c9c03a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En <a href=\"https:\/\/www.minejxsc.com\/es\/\">F\u00e1brica de maquinaria minera de JXSC <\/a>es un experimentado proveedor de equipos de miner\u00eda, especializado en diversos tipos de maquinaria eficaz en el procesamiento de minerales. Desde su fundaci\u00f3n en 1985, JXSC se ha ganado un gran respeto en el mercado internacional. Suministra equipos de miner\u00eda fiables y de alta calidad a m\u00e1s de 60 pa\u00edses.<\/p><p>JXSC ofrece soluciones completas de extracci\u00f3n de oro que incluyen concentraci\u00f3n por gravedad, separaci\u00f3n magn\u00e9tica y extracci\u00f3n hidrot\u00e9rmica. Esto significa que los equipos de JXSC est\u00e1n fabricados para mejorar la eficiencia de las operaciones mineras y poder procesar eficazmente incluso los yacimientos de oro m\u00e1s dif\u00edciles. Al trabajar con JXSC, las operaciones mineras pueden beneficiarse de tecnolog\u00eda punta, asesoramiento profesional y dedicaci\u00f3n a pr\u00e1cticas sostenibles y econ\u00f3micamente viables.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04d92be elementor-align-center elementor-widget elementor-widget-button\" data-id=\"04d92be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjQ2NTUiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Obtenga un presupuesto gratuito<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e31debf elementor-widget elementor-widget-heading\" data-id=\"e31debf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Preguntas frecuentes<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fdce26a elementor-widget elementor-widget-pp-faq\" data-id=\"fdce26a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;faq_layout&quot;:&quot;accordion&quot;,&quot;accordion_type&quot;:&quot;accordion&quot;,&quot;toggle_speed&quot;:300}\" data-widget_type=\"pp-faq.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"pp-faqs pp-advanced-accordion pp-toggle-icon-align-right\" id=\"pp-advanced-accordion-fdce26a\" data-accordion-id=\"fdce26a\">\n\t\t\t\t\t\t<div class=\"pp-faq-item elementor-grid-item pp-accordion-item\">\n\t\t\t\t<div id=\"pp-accordion-tab-title-2661\" class=\"pp-faq-question pp-accordion-tab-title\" tabindex=\"0\" data-tab=\"1\">\n\t\t\t\t\t<div class=\"pp-accordion-title-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-accordion-title-text\">\n\t\t\t\t\t\t\t\u00bfC\u00f3mo contribuyeron las erupciones volc\u00e1nicas a los yacimientos de oro?\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-accordion-toggle-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-close pp-icon'>\n\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-open pp-icon'>\n\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"pp-accordion-tab-content-2661\" class=\"pp-faq-answer pp-accordion-tab-content\" data-tab=\"1\">\n\t\t\t\t\t<div data-page-id=\"NfjtdkvF8odsI2xEU2PcBCwynQd\" data-docx-has-block-data=\"false\">\n<div class=\"ace-line ace-line old-record-id-CTr6duS1OoUiNoxpLcNcgWcanic\">El oro fue transportado a la superficie a trav\u00e9s de actividades volc\u00e1nicas que lo trajeron del manto terrestre. Los fluidos hidrotermales relacionados con la actividad volc\u00e1nica depositaron el oro en vetas dentro de las rocas y formaron yacimientos de alta ley que pudieron explotarse.<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"pp-faq-item elementor-grid-item pp-accordion-item\">\n\t\t\t\t<div id=\"pp-accordion-tab-title-2662\" class=\"pp-faq-question pp-accordion-tab-title\" tabindex=\"0\" data-tab=\"2\">\n\t\t\t\t\t<div class=\"pp-accordion-title-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-accordion-title-text\">\n\t\t\t\t\t\t\t\u00bfC\u00f3mo llega el oro a la Tierra desde el espacio?\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-accordion-toggle-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-close pp-icon'>\n\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-open pp-icon'>\n\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"pp-accordion-tab-content-2662\" class=\"pp-faq-answer pp-accordion-tab-content\" data-tab=\"2\">\n\t\t\t\t\t<div data-page-id=\"NfjtdkvF8odsI2xEU2PcBCwynQd\" data-docx-has-block-data=\"false\">\n<div class=\"ace-line ace-line old-record-id-T8NNdRwMHoyQfVxyUiecmr7RnRe\">El oro se forma en los entornos violentos de las supernovas y las colisiones entre estrellas de neutrones. Estas cosas ponen \u00e1tomos de oro por todas partes en el universo. Con el tiempo, algunas de estas part\u00edculas de oro quedan atrapadas en sistemas planetarios embrionarios . Los procesos geol\u00f3gicos y los impactos de meteoritos tambi\u00e9n concentran el oro en yacimientos alcanzables por la miner\u00eda.<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"pp-faq-item elementor-grid-item pp-accordion-item\">\n\t\t\t\t<div id=\"pp-accordion-tab-title-2663\" class=\"pp-faq-question pp-accordion-tab-title\" tabindex=\"0\" data-tab=\"3\">\n\t\t\t\t\t<div class=\"pp-accordion-title-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-accordion-title-text\">\n\t\t\t\t\t\t\t\u00bfTiene l\u00edmites la cantidad de oro en la Tierra?\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-accordion-toggle-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-close pp-icon'>\n\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class='pp-accordion-toggle-icon-open pp-icon'>\n\t\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg>\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<div id=\"pp-accordion-tab-content-2663\" class=\"pp-faq-answer pp-accordion-tab-content\" data-tab=\"3\">\n\t\t\t\t\t<div data-page-id=\"NfjtdkvF8odsI2xEU2PcBCwynQd\" data-docx-has-block-data=\"false\">\n<div class=\"ace-line ace-line old-record-id-UbbvdR2bloo8LRxmC0Zcujhmnhe\">S\u00ed, la cantidad de oro en la Tierra es finita. Cuanto m\u00e1s escasea, mayor es tambi\u00e9n su valor desde el punto de vista econ\u00f3mico. La utilizaci\u00f3n m\u00e1s eficiente de los recursos existentes depende de los avances tecnol\u00f3gicos que se realicen en las pr\u00e1cticas de miner\u00eda y extracci\u00f3n.<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a5419c elementor-widget elementor-widget-spacer\" data-id=\"7a5419c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5513d6e ignore-toc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5513d6e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ea2dbe9\" data-id=\"ea2dbe9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48de93e elementor-widget elementor-widget-heading\" data-id=\"48de93e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Comparte:<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-71bfada\" data-id=\"71bfada\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e65d1bb elementor-share-buttons--view-icon elementor-share-buttons--shape-rounded elementor-share-buttons--skin-gradient elementor-grid-0 elementor-share-buttons--color-official elementor-widget elementor-widget-share-buttons\" data-id=\"e65d1bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_facebook\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en facebook\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_linkedin\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en linkedin\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_twitter\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en twitter\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-twitter\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M459.37 151.716c.325 4.548.325 9.097.325 13.645 0 138.72-105.583 298.558-298.558 298.558-59.452 0-114.68-17.219-161.137-47.106 8.447.974 16.568 1.299 25.34 1.299 49.055 0 94.213-16.568 130.274-44.832-46.132-.975-84.792-31.188-98.112-72.772 6.498.974 12.995 1.624 19.818 1.624 9.421 0 18.843-1.3 27.614-3.573-48.081-9.747-84.143-51.98-84.143-102.985v-1.299c13.969 7.797 30.214 12.67 47.431 13.319-28.264-18.843-46.781-51.005-46.781-87.391 0-19.492 5.197-37.36 14.294-52.954 51.655 63.675 129.3 105.258 216.365 109.807-1.624-7.797-2.599-15.918-2.599-24.04 0-57.828 46.782-104.934 104.934-104.934 30.213 0 57.502 12.67 76.67 33.137 23.715-4.548 46.456-13.32 66.599-25.34-7.798 24.366-24.366 44.833-46.132 57.827 21.117-2.273 41.584-8.122 60.426-16.243-14.292 20.791-32.161 39.308-52.628 54.253z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_pinterest\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en pinterest\" data-no-translation-aria-label=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-pinterest\" viewbox=\"0 0 496 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M496 256c0 137-111 248-248 248-25.6 0-50.2-3.9-73.4-11.1 10.1-16.5 25.2-43.5 30.8-65 3-11.6 15.4-59 15.4-59 8.1 15.4 31.7 28.5 56.8 28.5 74.8 0 128.7-68.8 128.7-154.3 0-81.9-66.9-143.2-152.9-143.2-107 0-163.9 71.8-163.9 150.1 0 36.4 19.4 81.7 50.3 96.1 4.7 2.2 7.2 1.2 8.3-3.3.8-3.4 5-20.3 6.9-28.1.6-2.5.3-4.7-1.7-7.1-10.1-12.5-18.3-35.3-18.3-56.6 0-54.7 41.4-107.6 112-107.6 60.9 0 103.6 41.5 103.6 100.9 0 67.1-33.9 113.6-78 113.6-24.3 0-42.6-20.1-36.7-44.8 7-29.5 20.5-61.3 20.5-82.6 0-19-10.2-34.9-31.4-34.9-24.9 0-44.9 25.7-44.9 60.2 0 22 7.4 36.8 7.4 36.8s-24.5 103.8-29 123.2c-5 21.4-3 51.6-.9 71.2C65.4 450.9 0 361.1 0 256 0 119 111 8 248 8s248 111 248 248z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0073ecd ignore-toc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0073ecd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f986d41\" data-id=\"f986d41\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14d7fbd elementor-widget elementor-widget-heading\" data-id=\"14d7fbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Entradas relacionadas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d92e566 elementor-grid-4 elementor-grid-tablet-2 elementor-grid-mobile-1 pp-equal-height-yes elementor-widget elementor-widget-pp-posts\" data-id=\"d92e566\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-posts.portfolio\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"pp-posts-container\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t<div class=\"pp-posts pp-posts-skin-portfolio elementor-grid pp-posts-grid\" data-query-type=\"custom\" data-layout=\"grid\" data-page=\"10508\" data-skin=\"portfolio\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-post-wrap pp-grid-item-wrap elementor-grid-item post-55420 blog type-blog status-publish has-post-thumbnail hentry category-mineral-solution\">\n\t\t\t\t\t\t<div class=\"pp-post pp-grid-item\">\n\t\t\t\t<div class=\"pp-post-content pp-content-always\">\n\t\t\t\t\t\t\t<div class=\"pp-post-thumbnail\">\n\t\t\t<a class=\"pp-post-thumbnail-wrap\" href=\"https:\/\/www.minejxsc.com\/es\/blog\/4-common-silica-sand-impurities-best-removal-methods\/\" title=\"4\u00a0Common Silica Sand Impurities &amp; Best Removal Methods\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2026\/05\/Silica-Sand-Impurities.jpg\" class=\"attachment-large size-large wp-image-55421\" alt=\"Silica Sand Impurities\" srcset=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2026\/05\/Silica-Sand-Impurities.jpg 1024w, https:\/\/www.minejxsc.com\/wp-content\/uploads\/2026\/05\/Silica-Sand-Impurities-16x12.jpg 16w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"pp-image-overlay\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"pp-post-thumb-content-wrap\">\n\t\t\t\t\t\t<div class=\"pp-post-thumb-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"pp-post-title\">\n\t\t\t\t<a href=\"https:\/\/www.minejxsc.com\/es\/blog\/4-common-silica-sand-impurities-best-removal-methods\/\" target=\"_blank\">4\u00a0Common Silica Sand Impurities &amp; Best Removal Methods<\/a>\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t<div class=\"pp-post-meta\">\n\t\t\t\t\t\t\t\t<span class=\"pp-post-date\">\n\t\t\t\t\t\t<span class=\"pp-meta-text\">\n\t\t\t\tmayo 8, 2026\t\t\t<\/span>\n\t\t<\/span>\n\t\t<span class=\"pp-meta-separator\"><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"pp-post-wrap pp-grid-item-wrap elementor-grid-item post-55362 blog type-blog status-publish has-post-thumbnail hentry category-equipment-info\">\n\t\t\t\t\t\t<div class=\"pp-post pp-grid-item\">\n\t\t\t\t<div class=\"pp-post-content pp-content-always\">\n\t\t\t\t\t\t\t<div class=\"pp-post-thumbnail\">\n\t\t\t<a class=\"pp-post-thumbnail-wrap\" href=\"https:\/\/www.minejxsc.com\/es\/blog\/spiral-concentrator-low-cost-green-gravity-separator\/\" title=\"Spiral Concentrator: Low-Cost &amp; Green Gravity Separator\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2026\/04\/Spiral-concentrator.jpg\" class=\"attachment-large size-large wp-image-55363\" alt=\"Spiral concentrator\" srcset=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2026\/04\/Spiral-concentrator.jpg 1024w, https:\/\/www.minejxsc.com\/wp-content\/uploads\/2026\/04\/Spiral-concentrator-16x12.jpg 16w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"pp-image-overlay\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"pp-post-thumb-content-wrap\">\n\t\t\t\t\t\t<div class=\"pp-post-thumb-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"pp-post-title\">\n\t\t\t\t<a href=\"https:\/\/www.minejxsc.com\/es\/blog\/spiral-concentrator-low-cost-green-gravity-separator\/\" target=\"_blank\">Spiral Concentrator: Low-Cost &amp; Green Gravity Separator<\/a>\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t<div class=\"pp-post-meta\">\n\t\t\t\t\t\t\t\t<span class=\"pp-post-date\">\n\t\t\t\t\t\t<span class=\"pp-meta-text\">\n\t\t\t\tabril 28, 2026\t\t\t<\/span>\n\t\t<\/span>\n\t\t<span class=\"pp-meta-separator\"><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"pp-post-wrap pp-grid-item-wrap elementor-grid-item post-55262 blog type-blog status-publish has-post-thumbnail hentry category-mineral-solution\">\n\t\t\t\t\t\t<div class=\"pp-post pp-grid-item\">\n\t\t\t\t<div class=\"pp-post-content pp-content-always\">\n\t\t\t\t\t\t\t<div class=\"pp-post-thumbnail\">\n\t\t\t<a class=\"pp-post-thumbnail-wrap\" href=\"https:\/\/www.minejxsc.com\/es\/blog\/unlocking-high-grade-copper-the-power-of-ore-concentration\/\" title=\"Unlocking High-Grade Copper: The Power Of Ore Concentration\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2026\/04\/Unlocking-High-Grade-Copper-Ore-Concentration.jpg\" class=\"attachment-large size-large wp-image-55263\" alt=\"Unlocking High Grade Copper Ore Concentration\" srcset=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2026\/04\/Unlocking-High-Grade-Copper-Ore-Concentration.jpg 1024w, https:\/\/www.minejxsc.com\/wp-content\/uploads\/2026\/04\/Unlocking-High-Grade-Copper-Ore-Concentration-16x12.jpg 16w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"pp-image-overlay\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"pp-post-thumb-content-wrap\">\n\t\t\t\t\t\t<div class=\"pp-post-thumb-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"pp-post-title\">\n\t\t\t\t<a href=\"https:\/\/www.minejxsc.com\/es\/blog\/unlocking-high-grade-copper-the-power-of-ore-concentration\/\" target=\"_blank\">Unlocking High-Grade Copper: The Power Of Ore Concentration<\/a>\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t<div class=\"pp-post-meta\">\n\t\t\t\t\t\t\t\t<span class=\"pp-post-date\">\n\t\t\t\t\t\t<span class=\"pp-meta-text\">\n\t\t\t\tabril 20, 2026\t\t\t<\/span>\n\t\t<\/span>\n\t\t<span class=\"pp-meta-separator\"><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"pp-post-wrap pp-grid-item-wrap elementor-grid-item post-55201 blog type-blog status-publish has-post-thumbnail hentry category-equipment-info\">\n\t\t\t\t\t\t<div class=\"pp-post pp-grid-item\">\n\t\t\t\t<div class=\"pp-post-content pp-content-always\">\n\t\t\t\t\t\t\t<div class=\"pp-post-thumbnail\">\n\t\t\t<a class=\"pp-post-thumbnail-wrap\" href=\"https:\/\/www.minejxsc.com\/es\/blog\/impact-crusher-vs-cone-crusher-which-is-best-for-aggregates\/\" title=\"Impact Crusher Vs. Cone Crusher: Which Is Best For Aggregates?\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2026\/04\/Impact-Crusher-vs.-Cone-Crusher.jpg\" class=\"attachment-large size-large wp-image-55203\" alt=\"Impact Crusher vs. Cone Crusher\" srcset=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2026\/04\/Impact-Crusher-vs.-Cone-Crusher.jpg 1024w, https:\/\/www.minejxsc.com\/wp-content\/uploads\/2026\/04\/Impact-Crusher-vs.-Cone-Crusher-16x12.jpg 16w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"pp-image-overlay\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"pp-post-thumb-content-wrap\">\n\t\t\t\t\t\t<div class=\"pp-post-thumb-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h4 class=\"pp-post-title\">\n\t\t\t\t<a href=\"https:\/\/www.minejxsc.com\/es\/blog\/impact-crusher-vs-cone-crusher-which-is-best-for-aggregates\/\" target=\"_blank\">Impact Crusher Vs. Cone Crusher: Which Is Best For Aggregates?<\/a>\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t<div class=\"pp-post-meta\">\n\t\t\t\t\t\t\t\t<span class=\"pp-post-date\">\n\t\t\t\t\t\t<span class=\"pp-meta-text\">\n\t\t\t\tabril 14, 2026\t\t\t<\/span>\n\t\t<\/span>\n\t\t<span class=\"pp-meta-separator\"><\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"pp-screen-only elementor-screen-only\" aria-live=\"polite\" id=\"pp-post-carousel-status\">Showing Slide 1 of 5<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>El oro es un metal de transici\u00f3n con el s\u00edmbolo Au, derivado de la palabra latina para oro, Aurum, y el n\u00famero at\u00f3mico 79 en la tabla peri\u00f3dica. El oro es un elemento qu\u00edmico, un metal de color amarillo brillante...<\/p>","protected":false},"featured_media":10455,"template":"","categories":[19],"tags":[],"class_list":["post-10508","blog","type-blog","status-publish","has-post-thumbnail","hentry","category-mineral-solution"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unveiling the Process: How Is Gold Formed - JXSC<\/title>\n<meta name=\"description\" content=\"Discover how is gold formed in nature and unravel the fascinating process behind its creation. Find all the details on our blog.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.minejxsc.com\/es\/blog\/how-is-gold-formed\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unveiling the Process: How Is Gold Formed - JXSC\" \/>\n<meta property=\"og:description\" content=\"Discover how is gold formed in nature and unravel the fascinating process behind its creation. Find all the details on our blog.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.minejxsc.com\/es\/blog\/how-is-gold-formed\/\" \/>\n<meta property=\"og:site_name\" content=\"JXSC\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-17T02:58:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/06\/How-is-Gold-Formed2.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.minejxsc.com\\\/blog\\\/how-is-gold-formed\\\/\",\"url\":\"https:\\\/\\\/www.minejxsc.com\\\/blog\\\/how-is-gold-formed\\\/\",\"name\":\"Unveiling the Process: How Is Gold Formed - JXSC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.minejxsc.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.minejxsc.com\\\/blog\\\/how-is-gold-formed\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.minejxsc.com\\\/blog\\\/how-is-gold-formed\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.minejxsc.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/How-is-Gold-Formed2.webp\",\"datePublished\":\"2024-06-11T01:36:32+00:00\",\"dateModified\":\"2025-03-17T02:58:00+00:00\",\"description\":\"Discover how is gold formed in nature and unravel the fascinating process behind its creation. Find all the details on our blog.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.minejxsc.com\\\/blog\\\/how-is-gold-formed\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.minejxsc.com\\\/blog\\\/how-is-gold-formed\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.minejxsc.com\\\/blog\\\/how-is-gold-formed\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.minejxsc.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/How-is-Gold-Formed2.webp\",\"contentUrl\":\"https:\\\/\\\/www.minejxsc.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/How-is-Gold-Formed2.webp\",\"width\":1024,\"height\":768,\"caption\":\"How is Gold Formed(2)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.minejxsc.com\\\/blog\\\/how-is-gold-formed\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.minejxsc.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How Is Gold Formed: Exploring the Journey from Space to Earth\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.minejxsc.com\\\/#website\",\"url\":\"https:\\\/\\\/www.minejxsc.com\\\/\",\"name\":\"JXSC\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.minejxsc.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.minejxsc.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.minejxsc.com\\\/#organization\",\"name\":\"JXSC\",\"url\":\"https:\\\/\\\/www.minejxsc.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.minejxsc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.minejxsc.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/JXSC-LOGO-light.png\",\"contentUrl\":\"https:\\\/\\\/www.minejxsc.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/JXSC-LOGO-light.png\",\"width\":210,\"height\":50,\"caption\":\"JXSC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.minejxsc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desvelando el proceso: C\u00f3mo se forma el oro - JXSC","description":"Descubra c\u00f3mo se forma el oro en la naturaleza y desentra\u00f1e el fascinante proceso que hay detr\u00e1s de su creaci\u00f3n. Descubre todos los detalles en nuestro blog.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.minejxsc.com\/es\/blog\/how-is-gold-formed\/","og_locale":"es_ES","og_type":"article","og_title":"Unveiling the Process: How Is Gold Formed - JXSC","og_description":"Discover how is gold formed in nature and unravel the fascinating process behind its creation. Find all the details on our blog.","og_url":"https:\/\/www.minejxsc.com\/es\/blog\/how-is-gold-formed\/","og_site_name":"JXSC","article_modified_time":"2025-03-17T02:58:00+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/06\/How-is-Gold-Formed2.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.minejxsc.com\/blog\/how-is-gold-formed\/","url":"https:\/\/www.minejxsc.com\/blog\/how-is-gold-formed\/","name":"Desvelando el proceso: C\u00f3mo se forma el oro - JXSC","isPartOf":{"@id":"https:\/\/www.minejxsc.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.minejxsc.com\/blog\/how-is-gold-formed\/#primaryimage"},"image":{"@id":"https:\/\/www.minejxsc.com\/blog\/how-is-gold-formed\/#primaryimage"},"thumbnailUrl":"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/06\/How-is-Gold-Formed2.webp","datePublished":"2024-06-11T01:36:32+00:00","dateModified":"2025-03-17T02:58:00+00:00","description":"Descubra c\u00f3mo se forma el oro en la naturaleza y desentra\u00f1e el fascinante proceso que hay detr\u00e1s de su creaci\u00f3n. Descubre todos los detalles en nuestro blog.","breadcrumb":{"@id":"https:\/\/www.minejxsc.com\/blog\/how-is-gold-formed\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.minejxsc.com\/blog\/how-is-gold-formed\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.minejxsc.com\/blog\/how-is-gold-formed\/#primaryimage","url":"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/06\/How-is-Gold-Formed2.webp","contentUrl":"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2024\/06\/How-is-Gold-Formed2.webp","width":1024,"height":768,"caption":"How is Gold Formed(2)"},{"@type":"BreadcrumbList","@id":"https:\/\/www.minejxsc.com\/blog\/how-is-gold-formed\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.minejxsc.com\/"},{"@type":"ListItem","position":2,"name":"How Is Gold Formed: Exploring the Journey from Space to Earth"}]},{"@type":"WebSite","@id":"https:\/\/www.minejxsc.com\/#website","url":"https:\/\/www.minejxsc.com\/","name":"JXSC","description":"","publisher":{"@id":"https:\/\/www.minejxsc.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.minejxsc.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.minejxsc.com\/#organization","name":"JXSC","url":"https:\/\/www.minejxsc.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.minejxsc.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2022\/10\/JXSC-LOGO-light.png","contentUrl":"https:\/\/www.minejxsc.com\/wp-content\/uploads\/2022\/10\/JXSC-LOGO-light.png","width":210,"height":50,"caption":"JXSC"},"image":{"@id":"https:\/\/www.minejxsc.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.minejxsc.com\/es\/wp-json\/wp\/v2\/blog\/10508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.minejxsc.com\/es\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/www.minejxsc.com\/es\/wp-json\/wp\/v2\/types\/blog"}],"version-history":[{"count":0,"href":"https:\/\/www.minejxsc.com\/es\/wp-json\/wp\/v2\/blog\/10508\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.minejxsc.com\/es\/wp-json\/wp\/v2\/media\/10455"}],"wp:attachment":[{"href":"https:\/\/www.minejxsc.com\/es\/wp-json\/wp\/v2\/media?parent=10508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.minejxsc.com\/es\/wp-json\/wp\/v2\/categories?post=10508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.minejxsc.com\/es\/wp-json\/wp\/v2\/tags?post=10508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}